{"id":10420,"date":"2025-08-08T13:08:44","date_gmt":"2025-08-08T11:08:44","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=10420"},"modified":"2025-08-08T13:08:54","modified_gmt":"2025-08-08T11:08:54","slug":"mas-de-700-docentes-se-capacitaron-en-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2025\/08\/08\/mas-de-700-docentes-se-capacitaron-en-inteligencia-artificial\/","title":{"rendered":"M\u00e1s de 700 docentes se capacitaron en Inteligencia Artificial"},"content":{"rendered":"<div class=\"row ts-gutter-30 noticia\">\n<div class=\"col-lg-8 nota-left-section\">\n<div id=\"details-news-236178\" class=\"single-post\">\n<div class=\"post-content-area\">\n<div class=\"post-media\">La ministra de Educaci\u00f3n<strong>, Susana Montaldo<\/strong>, junto a la Legisladora,\u00a0<strong>Carolina Vargas Aignasse,<\/strong>\u00a0dieron la apertura oficial a la Jornada de Capacitaci\u00f3n Docente en Inteligencia Artificial.<\/div>\n<div class=\"articleBody\">\n<div>\n<p>Acompa\u00f1aron a la titular de la cartera educativa la secretaria de Estado de Educaci\u00f3n,\u00a0<strong>Gabriela Gallardo;<\/strong>\u00a0el vicepresidente del IDEP,<strong>\u00a0Juan Casa\u00f1as<\/strong>; el director Ejecutivo del IDEP,<strong>\u00a0Maximiliano Mart\u00ednez M\u00e1rquez;\u00a0<\/strong>la directora de Educaci\u00f3n Secundaria,\u00a0<strong>Rosa Casares;<\/strong>\u00a0la directora de J\u00f3venes y Adultos y Educaci\u00f3n No Formal,\u00a0<strong>Dora Villagra<\/strong>; la directora de Educaci\u00f3n Superior No Universitaria y Art\u00edstica,<strong>\u00a0Silvina Fern\u00e1ndez;<\/strong>\u00a0la subdirectora de Educaci\u00f3n P\u00fablica de Gesti\u00f3n Privada,\u00a0<strong>Guadalupe Corral<\/strong>; el coordinador Acad\u00e9mico del CIIDEPT,\u00a0<strong>Marcelo Ju\u00e1rez<\/strong>, legisladores, supervisores, directores, docentes y gremios.<\/p>\n<p>La capacitaci\u00f3n estuvo a cargo de los disertantes\u00a0<strong>Guadalupe Dorna,\u00a0<\/strong>directora de la Maestr\u00eda en Pol\u00edticas P\u00fablicas de la Universidad Torcuato Di Tella;\u00a0<strong>Emiliano Pereiro,<\/strong> jefe de Pensamiento Computacional e Inteligencia Artificial del Plan Ceibal (Uruguay) y un equipo de expertos del Ministerio de Educaci\u00f3n. Tucum\u00e1n es la primera provincia pionera en especializar a sus docentes en esta rama innovadora. Este primer encuentro otorg\u00f3 puntaje docente y reuni\u00f3 a cientos de educadores de toda la provincia, quienes se capacitaron de manera gratuita.<\/p>\n<p>Sobre la iniciativa, <strong>Susana Montaldo, expres\u00f3: \u201cEstoy muy contenta y celebro esto. Brindarle a los docentes el manejo de una herramienta que est\u00e1 entre nosotros revolucionar\u00e1 y cambiar\u00e1 los trabajos. Tenemos ni\u00f1os y j\u00f3venes en nuestras aulas y queremos darles la mejor educaci\u00f3n. La inteligencia artificial nos exige a tener una mirada cr\u00edtica y saber trabajar en colaboraci\u00f3n con otros. Esto tiene una gran importancia como cualquier trabajo colaborativo de los distintos organismos del estado nos permite llegar con instituciones que solo no hubi\u00e9ramos podido\u201d.<\/strong><\/p>\n<p>Por su parte, Carolina Vagas Aignase, cont\u00f3: <strong>\u201cLa ley est\u00e1 vigente en Tucum\u00e1n, establece la obligatoriedad de la formaci\u00f3n docente en inteligencia artificial, con el fin de brindarle a nuestros chicos y j\u00f3venes herramientas para el mundo laboral que se viene en un corto plazo. Hoy est\u00e1n presentes especialistas de Buenos Aires, Uruguay y un gabinete del Ministerio de educaci\u00f3n que ya viene realizando experiencias insipientes en inteligencia artificial, aplicada a la educaci\u00f3n\u201d.<\/strong><\/p>\n<p>La experta, Guadalupe Dorna, a\u00f1adi\u00f3: <strong>\u201cLa IA no reemplazar\u00e1 a los docentes, viene a ayudarlos a generar lo que sabemos hacer mejor. Esto aumentar\u00e1 la capacidad docente. Una de las caracter\u00edsticas que tiene esta tecnolog\u00eda es que democratiza el acceso a la \u00faltima tecnolog\u00eda para que todos se beneficien. La capacitaci\u00f3n es fundamental, no hay manera de ense\u00f1ar si nosotros no somos lo primeros en dominar esto. Hay que empoderar a los docentes, capacitarlos y darle herramientas para que luego lo compartan con los alumnos\u201d.<\/strong><\/p>\n<p>Finalmente, la docente<strong>\u00a0Constanza D\u00edaz<\/strong>, explic\u00f3: \u201cSoy docente del nivel primario, estoy en un colegio privado, ense\u00f1ando en primer grado. La IA est\u00e1 muy presente en mi cotidianidad, entonces poder llevar esto a las aulas, tener estrategias y herramientas para poder implementarlas me parece muy bien. Es muy bueno que llegue a todos los docentes, no todos tienen la posibilidad de adquirir un curso privado o pagar\u201d.<\/p>\n<p><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.comunicaciontucuman.gob.ar\/fotos\/notas\/2025\/08\/07\/250807161532_19451.jpeg\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Educaci\u00f3n, Susana Montaldo, junto a la Legisladora,\u00a0Carolina Vargas Aignasse,\u00a0dieron la apertura oficial a la Jornada de Capacitaci\u00f3n Docente en Inteligencia Artificial. Acompa\u00f1aron a la titular de la cartera educativa la secretaria de Estado de Educaci\u00f3n,\u00a0Gabriela Gallardo;\u00a0el vicepresidente del IDEP,\u00a0Juan Casa\u00f1as; el director Ejecutivo del IDEP,\u00a0Maximiliano Mart\u00ednez M\u00e1rquez;\u00a0la directora de Educaci\u00f3n Secundaria,\u00a0Rosa Casares;\u00a0la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":10421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,34],"tags":[396,397],"class_list":["post-10420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-locales","tag-ministra-de-educacion","tag-susana-montaldo"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10420"}],"version-history":[{"count":2,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10420\/revisions"}],"predecessor-version":[{"id":10423,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10420\/revisions\/10423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10421"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}