{"id":11663,"date":"2025-10-06T13:22:07","date_gmt":"2025-10-06T11:22:07","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=11663"},"modified":"2025-10-06T13:22:07","modified_gmt":"2025-10-06T11:22:07","slug":"hugo-moyano-echo-a-4-dirigentes-del-sindicato-de-camioneros","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2025\/10\/06\/hugo-moyano-echo-a-4-dirigentes-del-sindicato-de-camioneros\/","title":{"rendered":"Hugo Moyano ech\u00f3 a 4 dirigentes del Sindicato de Camioneros"},"content":{"rendered":"<header class=\"article-header-wrapper\">\n<div class=\"article-header\">\n<p class=\"article-subheadline text_align_left\">A los dos desplazados a principios de semana se sumaron otros dos. Se habla de irregularidades en el manejo de fondos de un hotel. La influencia de Octavio Arg\u00fcello y el papel de Pablo Moyano, como tel\u00f3n de fondo<\/p>\n<\/div>\n<\/header>\n<article class=\"article\">\n<div class=\"body-article \">\n<div class=\"visual__image image-initial-width\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=577&amp;height=324&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/HSDDTSBVJFABVEZ73VJNOWFOP4.jpg?auth=cb26fc19ce6f5e83f321e4d3bbcd7457d1f6e1feeb133842458826f616b9d69c&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" alt=\"Hugo Moyano, l\u00edder del Sindicato\" width=\"962\" height=\"541\" \/><\/picture>Hugo Moyano, l\u00edder del Sindicato de Camioneros; a la derecha, su hijo Jer\u00f3nimo<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El l\u00edder del Sindicato de Camioneros,<b>\u00a0Hugo Moyano,<\/b>\u00a0sigue tomando medidas dr\u00e1sticas:\u00a0<b>ya ech\u00f3 a dos dirigentes de su comisi\u00f3n directiva y ahora desplaz\u00f3 a otros dos,<\/b> en medio de inquietantes versiones sobre supuestos manejos irregulares de fondos del gremio.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">A comienzos de esta semana, el jefe sindical alej\u00f3 de sus puestos al secretario Administrativo de Camioneros,\u00a0<b>Claudio Balazic,<\/b>\u00a0y el secretario Tesorero,\u00a0<b>Paulo Villegas,<\/b>\u00a0y luego apart\u00f3 al prosecretario Administrativo,\u00a0<b>Alejandro Vanati,<\/b>\u00a0y a otro dirigente.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">No est\u00e1n claros los motivos de esta decisi\u00f3n porque hay mucho hermetismo, pero trascendi\u00f3 que los despidos estar\u00edan vinculados con una\u00a0<b>denuncia judicial\u00a0<\/b>que investiga un presunto fraude en el hotel 15 de Diciembre que el gremio tiene en Mar del Plata.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=992&amp;height=848&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=768&amp;height=656&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=577&amp;height=493&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=420&amp;height=359&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=350&amp;height=299&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/XNMDBT4PGJHCFD2NJFGWMJEKYE.png?auth=759ba56f72824c701a244b3d6b040ebc47ce3d2cbdf80f4c2c8b36d9609408ac&amp;smart=true&amp;width=350&amp;height=299&amp;quality=85\" alt=\"Claudio Balazic, uno de los\" width=\"509\" height=\"435\" \/><\/picture><\/div>\n<div class=\"visual__image\"><span style=\"font-size: 8pt;\"><strong>Claudio Balazic, uno de los dirigentes que fueron echados del Sindicato de Camioneros<\/strong><\/span><\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La investigaci\u00f3n judicial, seg\u00fan el diario La Naci\u00f3n, se inici\u00f3 el 12 de septiembre a partir de una denuncia presentada en la\u00a0<b>fiscal\u00eda N\u00b010 de Mar del Plata<\/b>, a cargo de\u00a0<b>Carlos David Bruna.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Dicen que el administrador del hotel fue expulsado del sindicato y denunciado, aunque su defensa argumenta que carec\u00eda de poder de decisi\u00f3n y que las acciones investigadas se habr\u00edan originado en la sede de la organizaci\u00f3n sindical en Buenos Aires. Entre los elementos bajo an\u00e1lisis judicial figuran\u00a0<b>cheques<\/b> firmados por los directivos desplazados. Simult\u00e1neamente, Camioneros comunic\u00f3 el\u00a0<b>cierre temporal<\/b>\u00a0del hotel para realizar\u00a0<b>\u201creformas\u201d.<\/b><\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=992&amp;height=647&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=768&amp;height=501&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=577&amp;height=376&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=420&amp;height=274&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=350&amp;height=228&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/XGHU2DLD3JG4TEMIOQEXWIJJCU.jpg?auth=6f2efee11cdf9b42a65daa9bbb66ab5e2c4f30ca7bcd12c8ad342e0d051a44ce&amp;smart=true&amp;width=350&amp;height=228&amp;quality=85\" alt=\"Hugo Moyano, con su hijo\" width=\"1920\" height=\"1252\" \/><\/picture>Hugo Moyano, con su hijo Jer\u00f3nimo y Octavio Arg\u00fcello<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Inicialmente circularon rumores de que los traum\u00e1ticos cambios obedec\u00edan al encumbramiento de\u00a0<b>Octavio Arg\u00fcello\u00a0<\/b>en el sindicato (\u00bfse encamina a ser el heredero elegido por el l\u00edder de 81 a\u00f1os?), para lo cual hab\u00eda que\u00a0<b>apartar\u00a0<\/b>a algunos integrantes del secretariado m\u00e1s cercanos a\u00a0<b>Pablo Moyano<\/b>\u00a0o sospechados de proveerle de fondos del gremio para su gesti\u00f3n en el club Deportivo Camioneros.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Incluso se comentaba que la verdadera inspiradora de los despidos fue la esposa de Hugo Moyano,\u00a0<b>Liliana Zulet,<\/b>\u00a0quien, enemistada a muerte con el hijo mayor de su marido, quer\u00eda borrar de la grilla sindical a quienes habr\u00edan permitido que el club presidido por Pablo se convirtiera en \u201cuna vidriera de una buena gesti\u00f3n\u201d: el s\u00e1bado pasado, Deportivo Camioneros obtuvo el campeonato de f\u00fatbol en la Primera C y de esa forma ascendi\u00f3 a la Primera B Metropolitana.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Las versiones en danza responden a la\u00a0<b>feroz interna\u00a0<\/b>que desat\u00f3 en Camioneros desde fines de 2021, cuando Pablo Moyano le\u00a0<b>recrimin\u00f3\u00a0<\/b>a Hugo el papel de su esposa, Liliana Zulet, en la\u00a0<b>profunda crisis financiera de la obra social camionera\u00a0<\/b>en su condici\u00f3n de due\u00f1a de la empresa IARAI, que se encarga de su\u00a0<b>gerenciamiento.<\/b><\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/T2JHA3ZMDRGABGNTGRCKS3OEVQ.jpg?auth=c3fec5837464effba75f3ffdcfad64d4d254d32b2fe2d470feef2f513f2242e3&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" alt=\"Hugo Moyano y su esposa\" width=\"1920\" height=\"1080\" \/><\/picture><span style=\"font-size: 8pt;\"><strong>Hugo Moyano y su esposa Liliana Zulet en la platea de Independiente<\/strong><\/span><\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Por eso Hugo Moyano\u00a0<b>desplaz\u00f3\u00a0<\/b>a Pablo de la secretar\u00eda adjunta de la Federaci\u00f3n de Trabajadores Camioneros en diciembre de 2021 y design\u00f3 en su lugar a\u00a0<b>Jorge Taboada,<\/b>\u00a0de Chubut. El d\u00edscolo hijo\u00a0<b>retuvo\u00a0<\/b>la secretar\u00eda adjunta del sindicato de Capital y Buenos Aires, pero el enfrentamiento con su pap\u00e1 hizo que<b>\u00a0dejara de ir a su oficina<\/b>\u00a0<b>y se dedicara a pleno a la presidencia del club Deportivo Camioneros.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El l\u00edder del sindicato, por su parte, reemplaz\u00f3 a su hijo en la CGT con un\u00a0<b>dirigente de confianza<\/b>\u00a0como Arg\u00fcello y \u00e9l mismo se sum\u00f3 a la mesa chica cegetista, mientras fue\u00a0<b>apartando\u00a0<\/b>en Camioneros a dirigentes de distintas ramas que respond\u00edan a su hijo.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En el Comit\u00e9 Central Confederal de la<b>\u00a0CGT<\/b>, realizado el 18 de septiembre pasado, Hugo Moyano le dedic\u00f3 una\u00a0<b>\u00e1spera frase a Pablo\u00a0<\/b>para justificar su alejamiento de la central obrera: \u201cUno de los secretarios generales se retir\u00f3 de la CGT. Ustedes deben recordarlo. Yo lo recuerdo. Mi hijo Pablo. \u00bfPor qu\u00e9?\u00a0<b>Porque tiene&#8230; ten\u00eda una forma poco&#8230; No digo violenta, pero un poco m\u00e1s dura porque no entend\u00eda que hab\u00eda cambiado esta sociedad y que hab\u00eda cambiado de otra manera.\u00a0<\/b>Por eso habl\u00e9 con los compa\u00f1eros primero y lo traje al compa\u00f1ero (en alusi\u00f3n a<b>\u00a0Arg\u00fcello).<\/b><\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/X7RALWUAGNEXPAH4QOANYTBTLA.jfif?auth=952c9d644b48e039c96b880f7e0b4b7aa239d9301d4cf1c544ee24493305625b&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" alt=\"Pablo Moyano, peleado por su\" width=\"960\" height=\"640\" \/><\/picture><span style=\"font-size: 8pt;\"><strong>Pablo Moyano, peleado por su padre y recluido en el f\u00fatbol<\/strong><\/span><\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">A algunos les pareci\u00f3\u00a0<b>un mensaje hacia la interna del sindicato,\u00a0<\/b>donde el jefe gremial promovi\u00f3 a\u00a0<b>otros de sus hijos:\u00a0<\/b>fueron ganando posiciones\u00a0<b>Hugo Antonio Moyano,<\/b>\u00a0abogado y candidato a diputado nacional de Fuerza Patria en el distrito bonaerense, y\u00a0<b>Jer\u00f3nimo Moyano,<\/b>\u00a0el menor de la familia y secretario de la Juventud de la Federaci\u00f3n de Camioneros.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Luego de su frase sobre Pablo, el l\u00edder sindical\u00a0<b>elogi\u00f3 en fuertes t\u00e9rminos a Arg\u00fcello:<\/b>\u00a0\u201cMuchas veces se destaca la actuaci\u00f3n del compa\u00f1ero, pero quiero decir algo que, que es muy importante.\u00a0<b>El compa\u00f1ero viene de la actividad m\u00e1s humilde que tiene nuestra actividad, la recolecci\u00f3n de residuos y, sin embargo, ha logrado ser diputado provincial, diputado nacional y hoy llega a la CGT.<\/b>\u00a0Porque conoce m\u00e1s que muchos de nosotros la realidad de lo que es vivir cuando el sueldo no alcanza\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Este significativo respaldo a la figura del sucesor de Pablo en la CGT tiene una explicaci\u00f3n: Hugo Moyano\u00a0<b>desisti\u00f3 de promover a Jer\u00f3nimo como secretario de la Juventud<\/b>\u00a0en la pr\u00f3xima central obrera y, en cambio,\u00a0<b>ratificar\u00e1 a Arg\u00fcello como el representante de Camioneros. <\/b>Hoy, Hugo Moyano afronta el\u00a0<b>duro desaf\u00edo<\/b>\u00a0de recomponer su liderazgo, desarticular a los sectores que pugnan por el regreso de Pablo y, ahora,\u00a0<b>dejar a salvo su propia figura<\/b>\u00a0del eventual esc\u00e1ndalo que desatar\u00eda la causa judicial en Mar del Plata.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>A los dos desplazados a principios de semana se sumaron otros dos. Se habla de irregularidades en el manejo de fondos de un hotel. La influencia de Octavio Arg\u00fcello y el papel de Pablo Moyano, como tel\u00f3n de fondo Hugo Moyano, l\u00edder del Sindicato de Camioneros; a la derecha, su hijo Jer\u00f3nimo El l\u00edder del &hellip;<\/p>\n","protected":false},"author":2,"featured_media":11664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,33],"tags":[1358],"class_list":["post-11663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-ganeral","category-nacionales","tag-hugo-moyano"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11663"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11663\/revisions"}],"predecessor-version":[{"id":11665,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11663\/revisions\/11665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11664"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}