{"id":13985,"date":"2026-01-22T12:42:54","date_gmt":"2026-01-22T11:42:54","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=13985"},"modified":"2026-01-22T12:42:54","modified_gmt":"2026-01-22T11:42:54","slug":"vuelven-el-futbol-de-la-afa-y-las-sospechas-que-diran-los-hinchas-sobre-chiqui-tapia","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2026\/01\/22\/vuelven-el-futbol-de-la-afa-y-las-sospechas-que-diran-los-hinchas-sobre-chiqui-tapia\/","title":{"rendered":"Vuelven el f\u00fatbol de la AFA y las sospechas: qu\u00e9 dir\u00e1n los hinchas sobre \u00abChiqui\u00bb Tapia"},"content":{"rendered":"<div class=\"pull-left col-md-6 fotos-containers\">\n<div class=\"container-fluid noPadding galeria_fotos_nota\">\n<div class=\"\">Vuelve el f\u00fatbol argentino. A simple vista, es una buena noticia: los equipos de nuestro medio salen a la cancha despu\u00e9s del receso estival, una antesala casera del Mundial de los Estados Unidos, M\u00e9xico y Canad\u00e1<b>.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13989 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810-1024x576.webp\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810-1024x576.webp 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810-300x169.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810-768x432.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810-390x220.webp 390w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/argentina-2026_1440x810.webp 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <\/b><\/div>\n<div class=\"\"><b>El formato no ayuda: la Liga Profesional insiste con la participaci\u00f3n de 30 equipos, divididos en dos zonas, con cruces mano a mano para definir al campe\u00f3n desde los octavos de final. El mismo sistema que consagr\u00f3 a Estudiantes (contra todos, contra todo) en el cierre de 2025, se renueva ahora con el torneo Apertura.<\/b><\/div>\n<\/div>\n<\/div>\n<p>El problema es todo lo dem\u00e1s: a menos de cinco meses de la defensa del t\u00edtulo de la selecci\u00f3n en Qatar, nadie habla de f\u00fatbol. Del juego, de los refuerzos, de la ilusi\u00f3n renovada.<br \/>\n<strong>Es que el Clausura estuvo motorizado por las sospechas. Equipos cercanos al poder, \u00e1rbitros c\u00f3mplices (o v\u00edctimas) de esa situaci\u00f3n y un tufillo de suspicacias que embarraron la cancha en casi todas las fechas. De lo urgente a lo importante: de fondo, la deste\u00f1ida imagen de Claudio Tapia, el presidente de la AFA, investigado por supuestos hechos il\u00edcitos. Todos los d\u00edas se conocen nuevas investigaciones de casos millonarios.<\/strong><br \/>\n\u00bfC\u00f3mo ser\u00e1 \u201crecibido\u201d el dirigente que sol\u00eda tomar mate con <strong>Lionel Messi y Rodrigo de Paul<\/strong> (y lo rubricaba en un posteo) en la previa de cada partido de la selecci\u00f3n? No solo fue cuestionado a viva voz con cierta dureza en la mayor\u00eda de los escenarios en el final del torneo anterior, sino que excedi\u00f3 el \u00e1mbito futbolero. En los recitales de m\u00fasica, por ejemplo<strong> (Andr\u00e9s Calamaro fue testigo en el Movistar Arena)<\/strong>, se enton\u00f3 la misma canci\u00f3n.<br \/>\n<strong>Los hinchas desconf\u00edan. Como nunca antes.<\/strong><br \/>\nSuele decirse en el folclore del f\u00fatbol (rubricado con episodios sobre el c\u00e9sped) que hay equipos cercanos al poder, como Barracas Central (el poder mismo, el hijo de Tapia, Mat\u00edas, preside la instituci\u00f3n del sur de la<strong> Ciudad de Buenos Aires), Rosario Central, Deportivo Riestra, Central C\u00f3rdoba de Santiago del Estero, Tigre y Argentinos Juniors.<\/strong> Ninguno de los cinco grandes. El enemigo p\u00fablico n\u00famero 1 es el Estudiantes del cr\u00edtico Juan Sebasti\u00e1n Ver\u00f3n, el conjunto que en el tramo final se consagr\u00f3 campe\u00f3n. Tiempo atr\u00e1s, alguien que supo combatirlo, como Andr\u00e9s Fassi, el presidente de Talleres, se rindi\u00f3 a sus pies. Defensor de un modelo empresarial, hoy es funcional.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13986 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/2fdp901l5_1256x620__1-1024x505.webp\" alt=\"\" width=\"1024\" height=\"505\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/2fdp901l5_1256x620__1-1024x505.webp 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/2fdp901l5_1256x620__1-300x148.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/2fdp901l5_1256x620__1-768x379.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/2fdp901l5_1256x620__1.webp 1256w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br \/>\n<strong>Las tareas de los \u00e1rbitros encabezan las sospechas. Fallos controvertidos, diferentes criterios para sancionar una id\u00e9ntica acci\u00f3n, desempe\u00f1os inconsistentes de quienes son designados para actuar en el VAR atraviesan al plantel que lideran Federico Beligoy, titular de la Direcci\u00f3n Nacional de Arbitraje y secretario general de la Asociaci\u00f3n Argentina de \u00c1rbitros, y Fernando Rapallini, en la funci\u00f3n de secretario t\u00e9cnico. Durante el verano, que suele ser un momento \u00f3ptimo para realizar una pretemporada, revisar conceptos y buscar una mayor transparencia, el silencio fue una marca registrada. No se supo nada de ellos p\u00fablicamente. Tapia-Toviggino fueron la portada exclusiva, al descubrirse una seguidilla de supuestos il\u00edcitos.<\/strong><br \/>\nLos cuestionamientos sobre los desempe\u00f1os arbitrales avanzan: se perdi\u00f3 credibilidad. Hay casos testigos, con nombre y apellido: Luis Lobo Medina, Andr\u00e9s Gariano, Nazareno Arasa, Pablo D\u00f3valo, Hern\u00e1n Mastr\u00e1ngelo, Andr\u00e9s Merlos, Fernando Espinoza, Nicol\u00e1s Lamolina y Pablo Echavarr\u00eda son algunos de ellos.<br \/>\n\u00bfCon qu\u00e9 \u00e1rbitros nos vamos a encontrar? \u00bfLos que dirigieron sensiblemente mal, envueltos en pol\u00e9micas con equipos ligados al poder o ser\u00e1n los que pasaron desapercibidos en el tramo final de los mata-mata?<br \/>\nEn realidad, fueron cuatro d\u00edas que lo cambiaron todo.<br \/>\n<strong>El 20 de noviembre, Rosario Central recibi\u00f3 una inesperada distinci\u00f3n por parte de la AFA: fue premiado como campe\u00f3n oficial de la temporada 2025 (\u201ccampe\u00f3n de liga\u201d) por haber finalizado primero en la Tabla Anual. No es la primera vez que la AFA cambia las reglas en medio de la competencia. Tres d\u00edas despu\u00e9s, por los octavos de final, Estudiantes debi\u00f3 hacerle \u201cel pasillo de campe\u00f3n\u201d a Central, pero lo hizo de espaldas, lo que provoc\u00f3 un revuelo may\u00fasculo. Luego, el Le\u00f3n se impuso por 1 a 0 en Arroyito. Esa imagen excedi\u00f3 el f\u00fatbol: la sociedad habl\u00f3 de Tapia como nunca antes.<\/strong><br \/>\nLa noche anterior, Central C\u00f3rdoba hab\u00eda eliminado a San Lorenzo, en Santiago del Estero. Hay que anclarse en este partido que empez\u00f3 a las 22 y termin\u00f3 el domingo de madrugada. San Lorenzo ganaba 1 a 0 y resist\u00eda los embates de Central C\u00f3rdoba. Hasta que apareci\u00f3 la figura de Nasareno Arasa, el \u00e1rbitro, uno de los m\u00e1s cuestionados. Primero, el contexto: el Cicl\u00f3n sol\u00eda recibir dinero de la AFA para pagar los sueldos de los jugadores, ya que viv\u00eda en una virtual acefal\u00eda. Y el equipo de Santiago del Estero tiene la simpat\u00eda de Pablo <strong>Toviggino, el tesorero de la AFA y la mano derecha de Chiqui Tapia.<\/strong><br \/>\n<strong>A los 17 minutos del segundo tiempo, el VAR llam\u00f3 a Arasa por un dudoso penal. Lo cobr\u00f3, a los 21: gol de Central C\u00f3rdoba. Luego de un encontronazo de Jhohan Roma\u00f1a con Mat\u00edas Perell\u00f3, el \u00e1rbitro le mostr\u00f3 la segunda amarilla al defensor colombiano: expulsado. Iban 25 minutos.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13988 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/zonas-torneo-apertura-2026-sorteo-futbol-argentino-jpg.webp\" alt=\"\" width=\"720\" height=\"405\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/zonas-torneo-apertura-2026-sorteo-futbol-argentino-jpg.webp 720w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/zonas-torneo-apertura-2026-sorteo-futbol-argentino-jpg-300x169.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/zonas-torneo-apertura-2026-sorteo-futbol-argentino-jpg-390x220.webp 390w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/strong><br \/>\nSe rompi\u00f3 el partido. Lo quebr\u00f3 el \u00e1rbitro. En el final, el equipo local marc\u00f3 el 2-1 y, acto seguido, el Cicl\u00f3n sufri\u00f3 otra expulsi\u00f3n. Termin\u00f3 con 9 jugadores. Hubo incidentes en el vestuario. Amenazas, protestas. San Lorenzo estaba en llamas: arriba (hab\u00eda \u201chinchas neutrales\u201d) y abajo. El dolor fue tan grande, que Pocho Cerutti y el pibe Gill se fueron entre l\u00e1grimas. Todos lloraban. No solo por la derrota.<br \/>\n<strong>A partir de ese encuentro, no hubo m\u00e1s pol\u00e9micas ni sospechas en todos los partidos que derivaron en la final en la que Estudiantes le gan\u00f3 a Racing. En el duelo entre la Academia y Tigre hubo una leve pol\u00e9mica por los dos expulsados en el gigante (sobre todo, Gast\u00f3n Martirena) y uno en Tigre. El resto de los encuentros fueron dirigidos de modo correcto, como si hubiera arrancado otro torneo.<\/strong><br \/>\nAntes, mucho antes, Barracas Central, el club se\u00f1alado a dedo, se clasific\u00f3 por primera vez a la Copa Sudamericana.<br \/>\n<strong>El Guapo fue beneficiado -al menos- en tres encuentros con decisiones arbitrales escandalosas. Ocurri\u00f3 en tres 1-1. En la fecha 10 del Clausura, Barracas se cit\u00f3 con Belgrano. Cuando se jugaban 43 minutos de la primera etapa lleg\u00f3 la jugada que gener\u00f3 la reacci\u00f3n de los cordobeses. Franco Jara aprovech\u00f3 un desentendimiento defensivo entre Yonatthan Rak y Nicol\u00e1s Demartini, que rechaz\u00f3 con cierta incomodidad. En ese momento, lleg\u00f3 Jara, trab\u00f3 y defini\u00f3.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13978 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/RvQd7dV2hJPl3tkWDwe3-2.gif\" alt=\"\" width=\"970\" height=\"90\" \/><\/strong><br \/>\nMientras Belgrano festejaba, Andr\u00e9s Gariano, el \u00e1rbitro, fue advertido por Adri\u00e1n Franklin, encargado del VAR. De inmediato, se dirigi\u00f3 a ver la jugada en el monitor y tras algunos instantes, cambi\u00f3 su fallo y expres\u00f3: \u201cLuego de la revisi\u00f3n en campo, veo falta en APP (Atacking Possession Phase o fase de ataque con posesi\u00f3n del bal\u00f3n) del n\u00famero 29 celeste en contra del 15 blanco. Decisi\u00f3n final, tiro libre directo\u201d.<br \/>\n<strong>La siguiente fue en la fecha 11 y el perjudicado fue Estudiantes. En el duelo disputado en La Plata, pas\u00f3 de todo. Lo ganaba el Le\u00f3n, pero en la jugada previa al empate se ve un claro contacto del atacante visitante Facundo Bruera sobre Facundo Rodr\u00edguez en la disputa de la pelota. Eso gener\u00f3 que el defensor de Estudiantes quedara en el piso, dolorido.<\/strong><br \/>\nLa jugada fue r\u00e1pida, pero termin\u00f3 en gol. Y a pesar de ese contacto, desde el VAR, a cargo de Jos\u00e9 Carreras, no se llam\u00f3 a Nazareno Arasa para que revisara la acci\u00f3n. Adem\u00e1s, hubo un empuj\u00f3n al arquero Muslera.<br \/>\nM\u00e1s tarde, Arasa volvi\u00f3 a ser protagonista en un tanto anulado a Estudiantes. Luego de un pelotazo desde la derecha, Carrillo asisti\u00f3 a Palacios, que convirti\u00f3 el 2-1. Sin embargo, el tanto fue revisado por el VAR y se anul\u00f3 por posici\u00f3n adelantada. El trazado de las l\u00edneas de TV s\u00f3lo provoca m\u00e1s suspicacias.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13880 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/oYztcBOLPiY2vSBuZXmE.gif\" alt=\"\" width=\"970\" height=\"90\" \/><br \/>\n<strong>Otro 1-1: Barracas Central y Hurac\u00e1n, por la 16\u00b0 fecha. El resultado determin\u00f3 la eliminaci\u00f3n del Globo rumbo a los playoffs. El protagonista fue \u2013otra vez- Andr\u00e9s Gariano, el \u00e1rbitro del encuentro, secundado por Jos\u00e9 Carreras, que estuvo a cargo del VAR. Los principales fallos del \u00e1rbitro: dos penales (mal) sancionados para el Guapo (uno de ellos atajado por Meza a Iv\u00e1n Tapia, el hijo del presidente de la AFA).<\/strong><br \/>\nEste jueves (un jueves arranca en el torneo\u2026), juegan Aldosivi-Defensa (a las 17), Banfield-Hurac\u00e1n y Uni\u00f3n-Platense (a las 20); Instituto-V\u00e9lez y Central C\u00f3rdoba-Gimnasia, de Mendoza, a las 22.15, seguramente ambos encuentros terminen en los primeros minutos del otro d\u00eda. El conjunto mendocino y Estudiantes de R\u00edo Cuarto son los nuevos habitantes de la m\u00e1xima categor\u00eda.<br \/>\n<strong>Algo m\u00e1s: son dos equipos que llegaron desde el ascenso (sobre todo, el cordob\u00e9s) con ciertas licencias.<\/strong><\/p>\n<p><span style=\"font-size: 8pt;\">\u00a0<\/span><a href=\"https:\/\/www.lanacion.com.ar\/deportes\/futbol\/vuelven-el-futbol-las-sospechas-y-una-intriga-como-sera-la-mirada-de-los-hinchas-con-chiqui-tapia-nid21012026\/\"><span style=\"font-size: 8pt;\">\u00a0\/La Naci\u00f3n<\/span><br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vuelve el f\u00fatbol argentino. A simple vista, es una buena noticia: los equipos de nuestro medio salen a la cancha despu\u00e9s del receso estival, una antesala casera del Mundial de los Estados Unidos, M\u00e9xico y Canad\u00e1. El formato no ayuda: la Liga Profesional insiste con la participaci\u00f3n de 30 equipos, divididos en dos zonas, con &hellip;<\/p>\n","protected":false},"author":2,"featured_media":13987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[294,33],"tags":[2906,904,2905],"class_list":["post-13985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol","category-nacionales","tag-afe","tag-mundial","tag-torneo-de-futbol"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13985"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13985\/revisions"}],"predecessor-version":[{"id":13990,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13985\/revisions\/13990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13987"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}