{"id":14339,"date":"2026-01-30T14:11:00","date_gmt":"2026-01-30T13:11:00","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=14339"},"modified":"2026-01-30T14:11:00","modified_gmt":"2026-01-30T13:11:00","slug":"ladrillos-hechos-con-residuos-de-la-cana-de-azucar","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2026\/01\/30\/ladrillos-hechos-con-residuos-de-la-cana-de-azucar\/","title":{"rendered":"Ladrillos hechos con residuos de la ca\u00f1a de az\u00facar"},"content":{"rendered":"<div class=\"pull-left col-md-6 fotos-containers\">\n<div class=\"container-fluid noPadding galeria_fotos_nota\">\n<div class=\"\"><b>La sustentabilidad est\u00e1 cobrando una importancia mayor en todos los sectores, y la construcci\u00f3n no es la excepci\u00f3n. Junto con la eficiencia y la accesibilidad se volvieron pilares fundamentales para la industria.<\/b><\/div>\n<\/div>\n<\/div>\n<p>Cada vez hay m\u00e1s opciones para innovar, e incluso los materiales m\u00e1s b\u00e1sicos, como la arcilla, el cemento o el hormig\u00f3n, pueden ser reemplazados.<br \/>\n<b>Un ejemplo de esto, son los nuevos ladrillos hechos con materiales reciclados y fibras naturales, como desechos de ca\u00f1a de az\u00facar, que tienen como objetivo reducir el impacto ambiental. Creados en Colombia por la empresa Green Solutions, se llaman Plock y prometen ser \u201cuna opci\u00f3n resistente, liviana y ecol\u00f3gica\u201d.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14342 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/el-ladrillo-que-esta-hecho-de-plastico-KQUCCNEKZJGQPNELV27W7OKY6I-1024x683.avif\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/el-ladrillo-que-esta-hecho-de-plastico-KQUCCNEKZJGQPNELV27W7OKY6I-1024x683.avif 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/el-ladrillo-que-esta-hecho-de-plastico-KQUCCNEKZJGQPNELV27W7OKY6I-300x200.avif 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/el-ladrillo-que-esta-hecho-de-plastico-KQUCCNEKZJGQPNELV27W7OKY6I-768x512.avif 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/el-ladrillo-que-esta-hecho-de-plastico-KQUCCNEKZJGQPNELV27W7OKY6I.avif 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/b><br \/>\nHay tres tipos de bloques, uno que simula el ladrillo com\u00fan y sirve para gran parte de la construcci\u00f3n, otro dise\u00f1ado para esquinas y medianeras, y el \u00faltimo utilizado en remate de muros y en la construcci\u00f3n de vanos para ventanas y puertas. A su vez, se puede elegir el tipo de acabado final: estuco, enchape cer\u00e1mico, entre otros.<br \/>\n<strong>Entre sus caracter\u00edsticas, la empresa colombiana destaca: el peso por m2 de muro, que en comparaci\u00f3n con el ladrillo tradicional de arcilla pesa 152 kg menos, pasando de 173kg a 21kg. A su vez, comentan que no necesitan mortero ni rellenos, obteniendo una reducci\u00f3n en materiales del 50%.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14343 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/Casas-hechas-con-resido-de-cana-de-azucar-1024x414.jpg\" alt=\"\" width=\"1024\" height=\"414\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/Casas-hechas-con-resido-de-cana-de-azucar-1024x414.jpg 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/Casas-hechas-con-resido-de-cana-de-azucar-300x121.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/Casas-hechas-con-resido-de-cana-de-azucar-768x310.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/Casas-hechas-con-resido-de-cana-de-azucar.jpg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/strong><br \/>\n\u201cLogramos reducir la huella de carbono en un 97% y la huella h\u00eddrica en un 90%, compar\u00e1ndolo con un ladrillo tradicional de arcilla\u00bb, declara en un comunicado, Walter Mu\u00f1oz, gerente de la empresa colombiana.<br \/>\n\u201cDesde el punto de vista social, al ser tan liviano puede llegar a los sitios m\u00e1s apartados del pa\u00eds donde vive la poblaci\u00f3n m\u00e1s vulnerable\u201d, agrega el empresario. Desde 2016, la empresa construy\u00f3 m\u00e1s de 200 viviendas con este material.<br \/>\n<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/resizer.glanacion.com\/resizer\/v2\/los-bloques-sugarcrete-estan-hechos-con-residuos-ODAKQAP2GNHUNG2FAYAOUZR6NA.jpg?auth=fec7e1c76607e10bc72d4d0bd020534799972408da1c54ba68a27ac3f97bc9b6&amp;width=780&amp;height=1170&amp;quality=70&amp;smart=true\" width=\"700\" \/><\/p>\n<div><span style=\"font-size: 8pt;\"><strong><i>Los bloques Sugarcrete est\u00e1n hechos con residuos de los cultivos de ca\u00f1a de az\u00facar<\/i><\/strong><\/span><\/div>\n<p>El cemento se posiciona como el elemento que m\u00e1s perjudica al medio ambiente, es por eso, que la industria est\u00e1 en una constante b\u00fasqueda de alternativas. <strong>El hormig\u00f3n (cemento, agua, arena y grava) es un material cuyo proceso de producci\u00f3n contribuye en un 8% a las emisiones de di\u00f3xido de carbono.<\/strong><br \/>\nPor lo que, diversos pa\u00edses experimentan con nuevas mezclas que puedan sustituir a este material, pero que tambi\u00e9n abaratan los costos, ya que utilizan residuos de otras industrias.<\/p>\n<div><b>En este caso, el material elegido para crear la mezcla fueron los residuos de los cultivos de ca\u00f1a de az\u00facar, (especialmente el bagazo) considerado el mayor del mundo por su cantidad de producci\u00f3n (2000 millones de toneladas al a\u00f1o). La elaboraci\u00f3n de Sugarcrete, el nombre que recibi\u00f3 este invento, implica unas emisiones de carbono 20 veces inferiores a las del hormig\u00f3n tradicional, es cinco veces m\u00e1s ligero y su producci\u00f3n es mucho m\u00e1s barata.\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Es utilizado para crear paneles aislantes, bloques ligeros de carga y losas estructurales para pisos y techos. Este proyecto fue llevado a cabo por arquitectos de la Universidad del Este de Londres (UEL), la empresa brit\u00e1nica Tate &amp; Lyle Sugars y la firma de arquitectura Grimshaw.<\/b><\/div>\n<div>Otra innovaci\u00f3n, con un impacto ecol\u00f3gico muy favorable, fue la primera baldosa y ladrillo de base biol\u00f3gica que crece con la ayuda de bacterias, llamada BioBasedTiles y creada en colaboraci\u00f3n con la startup estadounidense Biomason. Este producto, que utiliza biocemento para minimizar las emisiones de carbono, est\u00e1 inspirado en corales y ecosistemas marinos. <strong>Adem\u00e1s, se cura en 72 horas a temperatura ambiente y supera las propiedades de las baldosas fabricadas con hormig\u00f3n convencional una vez secas.<\/strong><\/div>\n<div><\/div>\n<p><b><u>Sustentabilidad en la Argentina<\/u><\/b><\/p>\n<p>Una arquitecta de Mar del Plata decidi\u00f3 pensar en un tipo de ladrillo biol\u00f3gico que sea de gran resistencia y completamente biodegradable. El puntapi\u00e9 de Juliana Lareu para ponerse en el rol de pionera en este campo fueron las investigaciones ya realizadas en otros pa\u00edses.<br \/>\n<strong>La ciudad balnearia fue su mejor aliada para lograrlo: los materiales del descarte de bagazo de cebada que desechan las f\u00e1bricas productoras de cerveza artesanal, junto a los desechos de virutas y aserr\u00edn provenientes de las madereras locales le ofrecieron a costo cero la materia prima.<\/strong><br \/>\nEl ingrediente fundamental es la ra\u00edz o micelio de hongos como el Ganoderma Lucidum (Reishi) y el Pleurotus Ostreatus (Hongos Ostra).<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14174 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/publicidades.imagen.afdf453de9248d2c.aW1hZ2VuLmdpZg-2.gif\" alt=\"\" width=\"728\" height=\"90\" \/><\/p>\n<p>\u201cEl mismo se alimenta de la materia de descarte y crece en forma de red aglomerando las part\u00edculas del biomaterial\u201d, detalla la arquitecta. <strong>\u00bfEl objetivo? \u201cPoder darle una segunda vida \u00fatil al gran volumen de residuos que se genera y dar respuesta a la crisis clim\u00e1tica a partir de la reutilizaci\u00f3n de los desechos org\u00e1nicos y trabajando en alianzas con organismos vivos, en este caso con el micelio, que es el filamento vegetativo de los hongos\u201d, sintetiza.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13819 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/placa-hcd.jpg\" alt=\"\" width=\"970\" height=\"222\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/placa-hcd.jpg 970w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/placa-hcd-300x69.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/01\/placa-hcd-768x176.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/strong><br \/>\nLas piezas de 250 gramos son m\u00e1s resistentes que el hormig\u00f3n y pueden soportar m\u00e1s de 400 kg de peso. Su porosidad le permite actuar tambi\u00e9n como aislante t\u00e9rmico y ac\u00fastico; puede flotar y es ign\u00edfugo, es decir, no emite llamas al exponerlo a altas temperaturas. <strong>Estas caracter\u00edsticas implican que tiene un potencial enorme para la construcci\u00f3n y el dise\u00f1o. \u201cSer\u00eda buen\u00edsimo que pueda reemplazar o ser una alternativa a materiales de construcci\u00f3n contempor\u00e1neos que son los que generan tanta contaminaci\u00f3n\u201d, observa.<\/strong><\/p>\n<div>Los ladrillos son biodegradables y 100% compostables, es decir, que \u201cuna vez cumplido su ciclo, cuando entra en contacto con la tierra se degrada y vuelve al medio en forma de abono\u201d, explica la arquitecta y profesora de la Universidad de Mar del Plata. \/<a href=\"https:\/\/www.lanacion.com.ar\/propiedades\/construccion-y-diseno\/como-son-los-materiales-de-construccion-hechos-con-cana-de-azucar-bacterias-o-desechos-de-cerveza-nid30012026\/\">La Naci\u00f3n<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La sustentabilidad est\u00e1 cobrando una importancia mayor en todos los sectores, y la construcci\u00f3n no es la excepci\u00f3n. Junto con la eficiencia y la accesibilidad se volvieron pilares fundamentales para la industria. Cada vez hay m\u00e1s opciones para innovar, e incluso los materiales m\u00e1s b\u00e1sicos, como la arcilla, el cemento o el hormig\u00f3n, pueden ser &hellip;<\/p>\n","protected":false},"author":2,"featured_media":14340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,33],"tags":[2957],"class_list":["post-14339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-ganeral","category-nacionales","tag-ladrillos-de-cana-de-azucar"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/14339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=14339"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/14339\/revisions"}],"predecessor-version":[{"id":14344,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/14339\/revisions\/14344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/14340"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=14339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=14339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=14339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}