{"id":16824,"date":"2026-05-13T08:10:13","date_gmt":"2026-05-13T11:10:13","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=16824"},"modified":"2026-05-13T08:10:13","modified_gmt":"2026-05-13T11:10:13","slug":"reforma-del-codigo-de-planeamiento-urbano","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2026\/05\/13\/reforma-del-codigo-de-planeamiento-urbano\/","title":{"rendered":"Reforma del C\u00f3digo de Planeamiento Urbano"},"content":{"rendered":"<div class=\"entry__metadata\">\n<p class=\"breadcrumbs\"><span class=\"breadcrumb_last\" aria-current=\"page\">Reforma del C\u00f3digo de Planeamiento Urbano: tres horas de debate, exposiciones y talleres con m\u00e1s de 70 asistentes fue el saldo de la segunda audiencia p\u00fablica.<\/span><\/p>\n<p class=\"breadcrumbs\"><span class=\"breadcrumb_last\" aria-current=\"page\"><strong>PUBLICIDAD<\/strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16425 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Loteo-las-pircas-1.jpg\" alt=\"\" width=\"970\" height=\"90\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Loteo-las-pircas-1.jpg 970w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Loteo-las-pircas-1-300x28.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Loteo-las-pircas-1-768x71.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/span><\/p>\n<p class=\"entry__date\" title=\"12\/05\/2026, 17:40\"><strong>M\u00e1s de tres horas de debate, exposiciones y talleres con m\u00e1s de 70 especialistas, ingenieros, arquitectos, funcionarios, concejales y representantes de universidades fue el saldo de la segunda audiencia p\u00fablica llevada adelante en el Concejo Deliberante de San Miguel de Tucum\u00e1n para la reforma del C\u00f3digo de Planeamiento Urbano.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16827 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3179-1.jpg-scaled-1.webp\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3179-1.jpg-scaled-1.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3179-1.jpg-scaled-1-300x200.webp 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/strong><i class=\"fa-regular fa-calendar\"><\/i><\/p>\n<\/div>\n<div class=\"entry__body\">\n<p>\u00abFue realmente un balance super importante, se ha llevado adelante con much\u00edsimo \u00e9xito gracias a la participaci\u00f3n de muchas instituciones, sobre todo con la exposici\u00f3n del C\u00e1mara de Empresas Privadas de la Construcci\u00f3n (CECOPRIT) y del Colegio de Corredores Inmobiliarios respecto a los aportes a los distintos ejes planteados.<\/p>\n<p><strong>PUBLICIDAD<\/strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16817 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-1024x288.webp\" alt=\"\" width=\"1024\" height=\"288\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-1024x288.webp 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-300x84.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-768x216.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-1536x432.webp 1536w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/img4-2048x576.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Estamos en la etapa mas extensa con las audiencias p\u00fablicas, esperamos dos por mes hasta llegar a un nuevo anteproyecto presentado en el recinto antes de fin de a\u00f1o\u00bb, celebr\u00f3 el presidente de la comisi\u00f3n especial de Reforma del C\u00f3digo de Planeamiento Urbano,\u00a0<strong>Facundo Vargas Aignasse<\/strong>.<\/p>\n<p><strong>Luis Lobo Chaklian<\/strong>, representante por la municipalidad en la comisi\u00f3n, celebr\u00f3 la decisi\u00f3n pol\u00edtica de avanzar con el proceso de reforma: \u00abestas audiencias y esta Reforma del C\u00f3digo de Planeamiento Urbano tienen una anuencia pol\u00edtica que es fundamental, el primer paso es la decisi\u00f3n pol\u00edtica tanto del presidente del Concejo Deliberante,\u00a0<strong>Fernando<\/strong>\u00a0<strong>Juri<\/strong>, como de la intendenta,\u00a0<strong>Rossana<\/strong>\u00a0<strong>Chahla<\/strong>, buscando la participaci\u00f3n amplia de distintos actores sociales.<\/p>\n<p><strong>PUBLICIDAD<\/strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16607 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/cafe-03-1024x207.jpg\" alt=\"\" width=\"1024\" height=\"207\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/cafe-03-1024x207.jpg 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/cafe-03-300x61.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/cafe-03-768x155.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/cafe-03.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Queremos audiencias con intercambios, con debates, buscando dar lugar a un nuevo C\u00f3digo con visi\u00f3n metropolitana, con perspectiva medioambiental, contemplando nuevas centralidades, el respeto al patrimonio y tener una ciudad inteligente, basada en datos. Son todos elementos fundamentales para trabajar junto a los servicios y a la infraestructura\u00bb.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/nHOYFDAIeXM?si=-bm_IMGE1rkFGF_E\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>La comisi\u00f3n especial para el Estudio, Evaluaci\u00f3n y Reforma del Actual C\u00f3digo de Planeamiento Urbano est\u00e1 conformada por los concejales Facundo Vargas Aignasse (presidente),\u00a0<strong>Gonzalo Carrillo Leito, Emiliano Vargas Aignasse, Gustavo Cobos, Ramiro Ortega, Carlos Ale, Federico Romano Norri, Leandro Arga\u00f1araz, Gast\u00f3n G\u00f3mez, Cristian Abel<\/strong>\u00a0y los funcionarios municipales<strong>\u00a0Luis Lobo Chaklian, Mar\u00eda Guadalupe Rearte, Marcelo Daniel Beccari y M\u00f3nica Gladys Alicia Ailan<\/strong>. Tambi\u00e9n participaron los concejales\u00a0<strong>Carlos Ale y Alfredo Ter\u00e1n de Zaval\u00eda<\/strong>.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16825 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3124-1.JPG-scaled-1.webp\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3124-1.JPG-scaled-1.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG_3124-1.JPG-scaled-1-300x200.webp 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>La primera exposici\u00f3n estuvo a cargo del arquitecto\u00a0<strong>Ezequiel<\/strong>\u00a0<strong>Coletti<\/strong>, arquitecta\u00a0<strong>Pilar Navarro<\/strong>\u00a0y de la licenciada\u00a0<strong>Soledad Chavanne<\/strong>, presidente, secretaria general y directora ejecutiva del CECOPRIT. Con el apoyo de una presentaci\u00f3n con im\u00e1genes y mapas de la ciudad plantearon los desaf\u00edos del sector, los espacios de la ciudad que podr\u00edan constituirse en nuevos ejes de crecimiento<strong>.<\/strong><\/p>\n<p><strong>PUBLICIDAD<\/strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16586 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033.jpg\" alt=\"\" width=\"1584\" height=\"396\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033.jpg 1584w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033-300x75.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033-1024x256.jpg 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033-768x192.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/05\/IMG-20260331-WA0033-1536x384.jpg 1536w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\" \/><\/p>\n<p><strong>Plantearon la importancia de la construcci\u00f3n como polo econ\u00f3mico provincial, sosteniendo que seg\u00fan n\u00fameros de 2023 la inversi\u00f3n en d\u00f3lares del sector privado de la construcci\u00f3n alcanz\u00f3 los 235 millones de d\u00f3lares, en comparaci\u00f3n con la exportaci\u00f3n citr\u00edcola que alcanz\u00f3 los 357 millones de d\u00f3lares y la producci\u00f3n sucroalcoholera, con 917 millones de d\u00f3lares.<\/strong><\/p>\n<p>A su turno, la licenciada\u00a0<strong>Romina<\/strong>\u00a0<strong>Gordillo<\/strong>, presidenta del Colegio de Corredores Inmobiliarios, plante\u00f3 la necesidad de mejorar la calidad de la seguridad, de la iluminaci\u00f3n y de los servicios en distintos puntos de la ciudad para impulsar la demanda de viviendas en distintos puntos de la ciudad.<\/p>\n<p><strong>Tenemos una ciudad hermosa que puede planificarse para mejorar la calidad de vida, por ello es importante trabajar en el transporte p\u00fablico. Necesitamos mas all\u00e1 de plantear los cambios del C\u00f3digo de Planeamiento Urbano que podamos contar con la voluntad pol\u00edtica, de gesti\u00f3n, para cuidar y revalorizar cada espacio que hoy tiene la ciudad, en sus calles, veredas, plazas, complejos deportivos, espacios verdes, sem\u00e1foros, gesti\u00f3n de servicios, infraestructura y m\u00e1s. La ciudad que buscamos es posible, lo imposible s\u00f3lo tarda un poco m\u00e1s\u00bb, finaliz\u00f3 como corolario.<\/strong><\/p>\n<p><strong>PUBLICIDAD<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16341 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-1024x589.jpg\" alt=\"\" width=\"1024\" height=\"589\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-1024x589.jpg 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-300x173.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-768x442.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-1536x883.jpg 1536w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2026\/04\/Screenshot_20260422_105453_WhatsApp-2048x1178.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Reforma del C\u00f3digo de Planeamiento Urbano: tres horas de debate, exposiciones y talleres con m\u00e1s de 70 asistentes fue el saldo de la segunda audiencia p\u00fablica. PUBLICIDAD M\u00e1s de tres horas de debate, exposiciones y talleres con m\u00e1s de 70 especialistas, ingenieros, arquitectos, funcionarios, concejales y representantes de universidades fue el saldo de la segunda &hellip;<\/p>\n","protected":false},"author":2,"featured_media":16826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,34],"tags":[2562,130],"class_list":["post-16824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-ganeral","category-locales","tag-codigo-de-planeamiento-urbano","tag-concejo-deliberante"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16824"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16824\/revisions"}],"predecessor-version":[{"id":16828,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16824\/revisions\/16828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16826"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}