{"id":1739,"date":"2024-03-14T12:06:21","date_gmt":"2024-03-14T11:06:21","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=1739"},"modified":"2024-03-14T12:06:21","modified_gmt":"2024-03-14T11:06:21","slug":"no-se-si-villarruel-quiere-desestabilizar-al-gobierno-de-milei","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2024\/03\/14\/no-se-si-villarruel-quiere-desestabilizar-al-gobierno-de-milei\/","title":{"rendered":"\u201cNo s\u00e9 si Villarruel quiere desestabilizar al Gobierno de Milei\u201d"},"content":{"rendered":"<header class=\"article-header-wrapper\">\n<div class=\"article-header \">\n<p id=\"jose-luis-espert:-&quot;no-se-si-villarruel-quiere-desestabilizar-al-gobierno-de-milei&quot;\" class=\"article-headline left \">Jos\u00e9 Luis Espert:\u00a0A horas de que se debata el contenido del mega DNU en el Senado, el diputado se\u00f1al\u00f3 que el tratamiento tendr\u00eda consecuencias pol\u00edticas.<\/p>\n<\/div>\n<\/header>\n<article class=\"article\">\n<div class=\"body-article\">\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Luego de que la vicepresidente\u00a0<b>Victoria Villarruel<\/b>\u00a0diera lugar a una sesi\u00f3n para tratar el\u00a0<b>mega DNU<\/b>, el diputado\u00a0<b>Jos\u00e9 Luis Espert<\/b>\u00a0cuestion\u00f3 el accionar pol\u00edtico de la titular de la C\u00e1mara de Senadores al ponderar que su decisi\u00f3n podr\u00eda ser contraproducente para las futuras decisiones y reformas que buscar\u00eda plantear el Gobierno. A pesar de que mostr\u00f3 su desacuerdo ante el camino que escogi\u00f3 la referente, puso en duda los rumores que indicaron que se habr\u00eda tratado de una t\u00e1ctica para desestabilizar al oficialismo. \u201c<b>No s\u00e9 si Victoria Villarruel quiere desestabilizar al Gobierno de Milei<\/b>\u201d, apunt\u00f3.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Horas despu\u00e9s de que el presidente\u00a0<a href=\"https:\/\/www.infobae.com\/politica\/2024\/03\/13\/javier-milei-apunto-contra-villarruel-por-impulsar-el-tratamiento-del-dnu-el-rechazo-significaria-un-grave-retroceso\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-mrf-link=\"https:\/\/www.infobae.com\/politica\/2024\/03\/13\/javier-milei-apunto-contra-villarruel-por-impulsar-el-tratamiento-del-dnu-el-rechazo-significaria-un-grave-retroceso\/\"><b>Javier Milei<\/b><\/a> apuntara que la posibilidad de que la ca\u00edda del proyecto \u201csignificar\u00eda un grave retroceso\u201d, el referente libertario remarc\u00f3 que no hay ning\u00fan tipo de certezas para afirmar que la segunda en la l\u00ednea del mando habr\u00eda conspirado contra la administraci\u00f3n que representa. \u201cYo podr\u00e9 estar cerca del Gobierno y del presidente, pero no soy parte del Poder Ejecutivo, puedo no saber cosas\u201d, infiri\u00f3 sobre su desconocimiento en la presunta interna que habr\u00eda dividido a los l\u00edderes de La Libertad Avanza (LLA). No obstante, reconoci\u00f3 que \u201ca la luz de esto, me genera dudas\u201d, en referencia al visto bueno que dio Villarruel para que se sesionara este mi\u00e9rcoles.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cHubo una decisi\u00f3n pol\u00edtica de la vicepresidenta\u201d, destac\u00f3 al se\u00f1alar que, tal como hab\u00eda convocado a debatir el contenido del DNU, la representante de la C\u00e1mara Alta podr\u00eda haber hecho lo mismo con los decretos que impuls\u00f3 Alberto Fern\u00e1ndez durante la gesti\u00f3n anterior. Incluso, el economista puso como ejemplo una sesi\u00f3n celebrada en noviembre, en d\u00f3nde se trataron aproximadamente 100 proyectos legislativos, para despu\u00e9s ratificar que no hab\u00eda dudas de que se trat\u00f3 de una v\u00eda que decidi\u00f3 la integrante del Poder Ejecutivo.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Despu\u00e9s de haber sido consultado sobre el tema durante la emisi\u00f3n del noticiero de LN+, Espert consider\u00f3 que Villarruel tendr\u00eda que haberse mantenido en su posici\u00f3n y evitar la sesi\u00f3n de ma\u00f1ana. De la misma manera, desminti\u00f3 el argumento de que estaba obligada a presidir la sesi\u00f3n si no quer\u00eda recibir una denuncia penal. Asimismo, remarc\u00f3 que el reglamento del Senado le otorgar\u00eda la posibilidad de rechazar la convocatoria, aunque cumpliera con todos los requisitos necesarios para tratar una iniciativa en el recinto.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\" lazyload\" src=\"https:\/\/www.infobae.com\/new-resizer\/M9lLW7sGirk5sXem_FgAFQ5HM6k=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg%20420w\" sizes=\"auto, (min-width: 1560px) 856px, (min-width: 1000px) calc(74.63vw - 293px), (min-width: 780px) calc(100vw - 376px), (min-width: 580px) calc(100vw - 32px), 100vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/M9lLW7sGirk5sXem_FgAFQ5HM6k=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 420w,https:\/\/www.infobae.com\/new-resizer\/COB2aVU63ZIqt3h0llesArvEedg=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 768w,https:\/\/www.infobae.com\/new-resizer\/EOpf1HpofQz12uxwCG6uxh-i5w4=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 992w,https:\/\/www.infobae.com\/new-resizer\/1kgl27Lj06HC166bwNH-jCENIzM=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 1200w,https:\/\/www.infobae.com\/new-resizer\/w-cShCCKH2cmdwGZziy-hlPjm-U=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 1440w\" alt=\"Jos\u00e9 Luis Espert con Javier Milei\" width=\"1369\" height=\"770\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/M9lLW7sGirk5sXem_FgAFQ5HM6k=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/QCOWF4BO6FFT3ICKAGKAWE2RKM.jpeg 420w\" \/>Jos\u00e9 Luis Espert con Javier Milei<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cNo ten\u00eda ninguna obligaci\u00f3n, si uno se atiene al reglamento de la C\u00e1mara de Senadores, a convocar a la sesi\u00f3n de ma\u00f1ana (por hoy) por m\u00e1s que se hayan juntado las cinco firmas\u201d, subray\u00f3 el diputado, quien afirm\u00f3 haber consultado sobre la cuesti\u00f3n con expertos en materia constitucional. Por este motivo, diferenci\u00f3 el funcionamiento del Senado al de Diputados al indicar que, si la situaci\u00f3n se hubiera planteado en la C\u00e1mara Baja,\u00a0<b>Mart\u00edn Menem<\/b>\u00a0no iba a tener otra alternativa que abrir la sesi\u00f3n y permitir el debate entre partidos.<\/p>\n<div class=\"recommended-card__info\"><span class=\"recommended-card__info-interest-you\">Te puede interesar:<\/span><span class=\"recommended-card__info-title\">La sesi\u00f3n de ma\u00f1ana en el Senado para tratar el DNU est\u00e1 en duda porque se podr\u00eda ausentar un miembro del oficialismo<\/span><\/p>\n<div class=\"recommended-card__info-button recommended-card__info-button--infobae\"><\/div>\n<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En l\u00ednea con el planteo formulado por el jefe de Estado, el referente liberal anticip\u00f3 que \u201c<b>si se cae el DNU, pol\u00edticamente es un golpe fuerte<\/b>\u201d, a la vez que se\u00f1al\u00f3 que ser\u00eda \u201cuna pena porque ese DNU tiene cosas muy buenas para la gente\u201d. De esta forma, interpret\u00f3 que la no aprobaci\u00f3n del proyecto beneficiar\u00eda a la casta pol\u00edtica, sindical y empresaria a la que el Gobierno busca desarticular. Adem\u00e1s, pronostic\u00f3 que un resultado negativo para el oficialismo tendr\u00eda un costo pol\u00edtico en los pr\u00f3ximos meses.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En paralelo, Espert critic\u00f3 el intento de presentar una nueva f\u00f3rmula de jubilaci\u00f3n en la C\u00e1mara de Diputados por parte de Hacemos Coalici\u00f3n Federal. \u201cEs una avivada, ir m\u00e1s r\u00e1pido lo que est\u00e1 yendo porque ya viene en la Ley Bases la f\u00f3rmula de jubilaci\u00f3n\u201d, consider\u00f3 el economista al destacar que fue una jugada pol\u00edtica orientada a \u201cdetonar el programa pol\u00edtico de Milei\u201d. Asimismo, indic\u00f3 que el tratamiento de la iniciativa no generar\u00eda grandes cambios, debido a que se pondr\u00eda en marcha a partir del 1\u00b0 de abril de ser aprobada.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Frente a esto, el liberal asegur\u00f3 que fue irresponsable por parte de los diputados anunciar que habr\u00eda un aumento a jubilados, sobre todo, porque el proyecto no consideraba que recortes en gasto p\u00fablico se har\u00edan para compensar el cambio en la redistribuci\u00f3n del presupuesto. \u201c<b>Si no hay plata, si el Gobierno est\u00e1 ajustando, vos no pod\u00e9s salir con un aumento a jubilados que encima es re sensible<\/b>\u201d, ponder\u00f3.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Por \u00faltimo, Espert plante\u00f3 que la aprobaci\u00f3n de la f\u00f3rmula de jubilaci\u00f3n que idearon desde la oposici\u00f3n podr\u00eda haber repercutido en la relaci\u00f3n con los gobernadores. \u201cLa f\u00f3rmula jubilatoria ya est\u00e1 dentro de la Ley Bases que es la que se est\u00e1 discutiendo con los gobernadores, quienes fueron los que le dijeron a sus diputados que no votaron la primera versi\u00f3n\u201d, analiz\u00f3 sobre los cruces y repercusiones que gener\u00f3 la Ley \u00d3mnibus durante las sesiones extraordinarias.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Luis Espert:\u00a0A horas de que se debata el contenido del mega DNU en el Senado, el diputado se\u00f1al\u00f3 que el tratamiento tendr\u00eda consecuencias pol\u00edticas. Luego de que la vicepresidente\u00a0Victoria Villarruel\u00a0diera lugar a una sesi\u00f3n para tratar el\u00a0mega DNU, el diputado\u00a0Jos\u00e9 Luis Espert\u00a0cuestion\u00f3 el accionar pol\u00edtico de la titular de la C\u00e1mara de Senadores al &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,25],"tags":[316],"class_list":["post-1739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-politica","tag-jose-luis-espert"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1739"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1739\/revisions"}],"predecessor-version":[{"id":1741,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1739\/revisions\/1741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/1740"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}