{"id":2959,"date":"2024-05-21T14:18:48","date_gmt":"2024-05-21T12:18:48","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=2959"},"modified":"2024-05-21T14:18:48","modified_gmt":"2024-05-21T12:18:48","slug":"siempre-te-tuve-ganas-va-a-estar-todo-bien","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2024\/05\/21\/siempre-te-tuve-ganas-va-a-estar-todo-bien\/","title":{"rendered":"\u201cSiempre te tuve ganas, va a estar todo bien\u201d"},"content":{"rendered":"<header class=\"article-header-wrapper\">\n<div class=\"article-header \">\n<p id=\"&quot;siempre-te-tuve-ganas-va-a-estar-todo-bien&quot;:-procesaron-por-abuso-sexual-al-intendente-de-la-matanza-fernando-espinoza\" class=\"article-headline left \">Procesaron por abuso sexual al intendente de La Matanza Fernando Espinoza. <em><strong>La denuncia, hecha en 2021, fue radicada por una joven que trabajaba como secretaria privada del jefe comunal.<\/strong><\/em> En la causa, el intendente neg\u00f3 los hechos, pero la jueza no le crey\u00f3.<\/p>\n<\/div>\n<\/header>\n<article class=\"article\">\n<div class=\"body-article\">\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/pA3lJqgSgi8e1zuptIaT5pdMJRo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif%20420w\" sizes=\"auto, (min-width: 1560px) 856px, (min-width: 1000px) calc(74.63vw - 293px), (min-width: 780px) calc(100vw - 376px), (min-width: 580px) calc(100vw - 32px), 100vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/pA3lJqgSgi8e1zuptIaT5pdMJRo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 420w,https:\/\/www.infobae.com\/new-resizer\/jJrWf7SfU_eaKXWWjMTmMaBxc2s=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 768w,https:\/\/www.infobae.com\/new-resizer\/cJvvyTi4RojYUPSqSCE3anUV64k=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 992w,https:\/\/www.infobae.com\/new-resizer\/fS440AccyI7blwYauXTfkfqYFjI=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 1200w,https:\/\/www.infobae.com\/new-resizer\/_35KWVNpMA9oXaWbgTlRwUqpTfg=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 1440w\" alt=\"Fernando Espinoza, intendente de La Matanza\" width=\"1280\" height=\"853\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/pA3lJqgSgi8e1zuptIaT5pdMJRo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IKGDY6Y7MVGXLOAV2IJ4V4DTQU.jfif 420w\" \/>Fernando Espinoza, intendente de La Matanza<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>Una jueza proces\u00f3 por abuso sexual y desobediencia al intendente de La Matanza Fernando Espinoza<\/b>, a ra\u00edz de una denuncia que hab\u00eda radicado en su contra una joven, novia de un empresario amigo, que trabajaba bajo sus \u00f3rdenes\u00a0<b>como secretaria privada en el municipio<\/b>. La magistrada no orden\u00f3 la detenci\u00f3n del jefe comunal pero mantuvo la prohibici\u00f3n de contacto con la v\u00edctima y dispuso un embargo de $1.500.000, seg\u00fan se desprende del fallo<b>.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Al declarar en la causa, Espinoza rechaz\u00f3 los cargos en su contra. \u201cEl relato de la v\u00edctima asegurando haber sufrido esos tocamientos imp\u00fadicos sobre su cuerpo sin autorizaci\u00f3n, se encuentra respaldado con las conclusiones de los especialistas en la materia que la entrevistaron durante el desarrollo de la pesquisa\u201d, dijo la magistrada.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cHabr\u00e9 de tomar\u00a0<b>el descargo del imputado como un vano intento de mejorar su comprometida situaci\u00f3n procesal<\/b>, habida cuenta que basa su defensa en cuestionar a la v\u00edctima a lo largo del desarrollo de esta causa, realizando un juicio de valor sobre el modo en el que (la v\u00edctima) debi\u00f3 reaccionar frente a los hechos denunciados -lo que para el tribunal no deja m\u00e1s que entrever el temor por ella vivenciado justamente a ra\u00edz de lo ocurrido-, sin que sus dichos en rigor de verdad, encuentren asidero en alguna otra prueba en autos\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La denuncia, que se radic\u00f3 hace tres a\u00f1os, estuvo a punto de cerrarse por pedido de la fiscal\u00eda porque la v\u00edctima se hab\u00eda ido del pa\u00eds y no hab\u00eda impulsado la acci\u00f3n. Pero tras idas y vueltas la jueza\u00a0<b>Mar\u00eda Fabiana Galletti<\/b>\u00a0orden\u00f3 el procesamiento del jefe comunal del peronismo por \u201c<b>abuso sexual simple\u201d y \u201cdesobediencia\u201d,\u00a0<\/b>por haber intentando a la joven despu\u00e9s de que radicara la denuncia y pesara una orden de restricci\u00f3n.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/ZzT4HwS8Gk_pS3VZ-KvRoEZ4Ydo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png%20420w\" sizes=\"auto, (min-width: 1560px) 856px, (min-width: 1000px) calc(74.63vw - 293px), (min-width: 780px) calc(100vw - 376px), (min-width: 580px) calc(100vw - 32px), 100vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/ZzT4HwS8Gk_pS3VZ-KvRoEZ4Ydo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 420w,https:\/\/www.infobae.com\/new-resizer\/uwvue-O8jRfi2_jP9HzFpWltE_o=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 768w,https:\/\/www.infobae.com\/new-resizer\/mBUWK-lHH7Kuk0WlXZYpW-6NSUk=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 992w,https:\/\/www.infobae.com\/new-resizer\/K8851kc6_wvtfrYoE72HAFnW3gE=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 1200w,https:\/\/www.infobae.com\/new-resizer\/lK2xT2DJMHX8qRcIVBIlcrRKnp8=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 1440w\" alt=\"Espinoza, intendente bonaerense\" width=\"1620\" height=\"1080\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/ZzT4HwS8Gk_pS3VZ-KvRoEZ4Ydo=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/SGT5RSNWAFHGBHAX57PLAMNNAI.png 420w\" \/><\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Seg\u00fan consta en la causa, la joven M.J.R. asegur\u00f3 que el dirigente peronista la abus\u00f3 sexualmente mediante tocamientos en el interior del departamento donde viv\u00eda en la Capital Federal, el 10 de mayo de 2021. El intendente hab\u00eda ido a su casa despu\u00e9s de decirle que quer\u00eda cenar con ella. Ella cont\u00f3 que hab\u00eda comenzado a trabajar en la Municipalidad el 28 de abril de 2021, que la contrataci\u00f3n fue \u201cen negro\u201d dado que nunca la registraron, que la llamaban por un nombre falso \u201cdesconociendo las razones a las que ello obedec\u00eda y que deb\u00eda desempe\u00f1arse como secretaria privada con una remuneraci\u00f3n prometida de $150.000 mensuales\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En su denuncia afirm\u00f3 que el 3 de mayo durante una jornada de trabajo, el imputado le refiri\u00f3 que esa noche cenar\u00edan en su casa, lo que la tom\u00f3 por sorpresa porque parec\u00eda una imposici\u00f3n. Ella le dijo que no entend\u00eda y Espionoza le respondi\u00f3 \u201cqu\u00e9 cosa no entend\u00eda\u201d. Ella dijo que sinti\u00f3 que no ten\u00eda otra opci\u00f3n. Su novio le dijo que era normal la situaci\u00f3n y que no pod\u00eda ir a un restaurante porque era una persona p\u00fablica. Afirm\u00f3 que esa noche \u201ccenaron normalmente, pero que se sinti\u00f3 muy inc\u00f3moda\u201d. A los pocos d\u00edas la escena se repiti\u00f3. Incluso crey\u00f3 que el imputado le pon\u00eda \u201calgo\u201d en la bebida, pero que durante esa noche no se \u201cpropas\u00f3\u201d con ella, s\u00f3lo le hizo preguntas de car\u00e1cter muy personal. Ella le record\u00f3 que estaba en pareja desde hac\u00eda seis a\u00f1os. La tercera vez fue el episodio en que se centra la denuncia.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Durante la madrugada del d\u00eda 11 de mayo, seg\u00fan relat\u00f3 la v\u00edctima, el imputado refiri\u00f3 tener dolores cervicales y de espalda. Afirm\u00f3 que estaba contracturado y ella le ofreci\u00f3 un remedio. Pero Espinoza le pidi\u00f3 masajes. Ella le dijo que no y lo mando a descansar, pero la respuesta fue:<b>\u00a0\u201cNo tengas miedo, dale\u201d.\u00a0<\/b>De manera intimidante se desabroch\u00f3 la camisa, afirma la denuncia. Le dijo que no tuviera miedo porque \u201c<b>las mujeres de sus amigos ten\u00edan bigote\u201d<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cFernando, no s\u00e9 qu\u00e9 vas a hacer pero te pido que no, te pido que te vayas de mi casa\u201d y \u201cque estaba todo bien pero no se sent\u00eda c\u00f3moda \u201c, le dijo la joven, seg\u00fan su denuncia. Pero Espinoza \u201cuna vez dentro de la habitaci\u00f3n se quit\u00f3 el pantal\u00f3n, la camisa que previamente se hab\u00eda desabotonado y qued\u00f3 en ropa interior\u201d. Cuando volvi\u00f3 a pedirle que se fuera, \u201cel imputado la sujet\u00f3 fuertemente, indicando la v\u00edctima que no recordaba exactamente c\u00f3mo pas\u00f3, pero que \u00e9l logr\u00f3 terminar encima de ella en la cama\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Y durante ese lapso, el imputado comenz\u00f3 a besarle la zona de sus pechos y a tocarla por encima de la ropa mientras le dec\u00eda \u201c<b>QU\u00c9DATE TRANQUILA, SIEMPRE TE TUVE GANAS, VA A ESTAR TODO BIEN\u201d y le ped\u00eda que le practicara sexo oral<\/b>, intentando a su vez quitarle las prendas que vest\u00eda en contra de su voluntad, lo que habr\u00eda llevado a que le rompiera la camisa que ella ten\u00eda puesta, adem\u00e1s de intentar bajarse su propia ropa interior, lo que no consigui\u00f3 porque la v\u00edctima hac\u00eda fuerza para impedirlo.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Frente a la negativa, el jefe comunal se ofusco y dijo: \u201c<b>BUENO LISTO YA EST\u00c1 SE TERMIN\u00d3 TODO, ME VOY, YA EST\u00c1 NO TE PREOCUPES\u201d.\u00a0<\/b>La v\u00edctima asegur\u00f3: \u201cMe lo dijo de una manera amenazante, como un tono de poder que \u00e9l sab\u00eda que es mi jefe\u201d. Hubo una discusi\u00f3n. \u201cMe sent\u00ed ultrajada. No ten\u00eda, eh, ese se\u00f1or me quit\u00f3 las ganas de todo\u201d. La joven le pregunto si la iba a echar, y el intendente le respondi\u00f3 que no, que \u201clo que pasa en el trabajo es cosa de trabajo\u201d. Cuando se iba, \u201cenojado con mirada agresiva y de tono amenazante, \u00e9l me dijo: <strong>\u201cSOS UNA BOLUDA, NO SABES LO QUE TE PERD\u00c9S PERO BUENO, ALL\u00c1 VOS\u201d.<\/strong> Afirm\u00f3 que tuvo miedo y hasta pens\u00f3 en suicidarse. A los pocos d\u00edas le dijeron que en el trabajo estaba haciendo las cosas mal y que ten\u00eda los d\u00edas contados, \u201clo que interpret\u00f3 como una amenaza de muerte\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El\u00a0<b>segundo hecho por el que fue denunciado Espinoza\u00a0<\/b>sostiene que el 1 de julio de 2021, en horas de la tarde, cuando ya pesaba una orden de restricci\u00f3n en su contra a ra\u00edz de la denuncia, el intendente la habr\u00eda vuelto a contactar.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/KNiepxXDc-Ou_VHkQBNOQ8p6XNg=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG%20420w\" sizes=\"auto, (min-width: 1560px) 856px, (min-width: 1000px) calc(74.63vw - 293px), (min-width: 780px) calc(100vw - 376px), (min-width: 580px) calc(100vw - 32px), 100vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/KNiepxXDc-Ou_VHkQBNOQ8p6XNg=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 420w,https:\/\/www.infobae.com\/new-resizer\/G4pjlTc-TUJST-D-TXOY4UZOPzU=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 768w,https:\/\/www.infobae.com\/new-resizer\/NeV080hsTiku6doyN8yYBz1dRrg=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 992w,https:\/\/www.infobae.com\/new-resizer\/PWINTfwFdih6Rkljq_yzHTPXS8E=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 1200w,https:\/\/www.infobae.com\/new-resizer\/d_rU_WwMbY2qk0lt-djLpZwOJ94=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 1440w\" alt=\"Fernando Espinoza (Foto: Franco Fafasuli\/Archivo)\" width=\"1616\" height=\"1080\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/KNiepxXDc-Ou_VHkQBNOQ8p6XNg=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/IXTEI5XCKBDHTK2S7GNBMYNBHQ.JPG 420w\" \/>Fernando Espinoza (Foto: Franco Fafasuli\/Archivo)<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cLlegado el momento de resolver la situaci\u00f3n procesal de Tom\u00e1s Fernando Espinoza adelanto que se lo procesar\u00e1 (&#8230;). Debe aclararse que en este tipo de delitos donde la experiencia ha demostrado que se desarrollan en un \u00e1mbito de absoluta intimidad sin la presencia de testigos, los hechos comienzan a definirse desde la persona abusada, es decir desde la v\u00edctima. N\u00f3tese que aqu\u00ed la propia damnificada indic\u00f3 respecto al hecho 1, que ocurri\u00f3 mientras se encontraba a solas con el imputado en el interior de su departamento. Por lo tanto, en los delitos contra la integridad sexual, el testimonio de la v\u00edctima resulta naturalmente una prueba dirimente, toda vez que son hechos que, por su propia naturaleza, suelen tener lugar en \u00e1mbitos de intimidad y confianza, exento de las miradas de terceros\u201d, se sostuvo en el\u00a0<b>fallo<\/b>.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Para la jueza, \u201cm\u00e1s all\u00e1 que el accionar desplegado concretamente por el imputado no haya sido observado por terceras personas que pudieran atestiguar sobre ello, resultado que probablemente haya pretendido al efectuar los tocamientos lejos de la mirada ajena como suele ocurrir generalmente en este tipo de episodios, aprovechando la circunstancia de que se encontraba a solas con ella en el interior de su departamento porque, como indic\u00f3 (la v\u00edctima), se trataba de la tercera -y \u00faltima- vez que concurr\u00eda forzando prepotentemente los encuentros; ello, no resulta \u00f3bice para arribar al temperamento que aqu\u00ed pregono. Ello por cuanto, el relato de la v\u00edctima asegurando haber sufrido esos tocamientos imp\u00fadicos sobre su cuerpo sin autorizaci\u00f3n, se encuentra respaldado con las conclusiones de los especialistas en la materia que la entrevistaron durante el desarrollo de la pesquisa\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>La magistrada rechaz\u00f3 la versi\u00f3n de Espinoza<\/b>. \u201cLa hip\u00f3tesis defensista se bas\u00f3 en negar que la v\u00edctima cumpli\u00f3 tareas en el Municipio, pero luego se reconoci\u00f3 que s\u00ed trabaj\u00f3 y por el breve lapso de 15 d\u00edas aunque indicando que no se formaliz\u00f3 el empleo porque \u2018ella no realiz\u00f3 los tr\u00e1mites habilitantes\u2019 (cuesti\u00f3n que, de acreditarse, s\u00f3lo pondr\u00eda en evidencia de alg\u00fan modo la informalidad en la modalidad laboral). Tambi\u00e9n, se intent\u00f3 negar la concurrencia del imputado al departamento de la v\u00edctima alegando que todo lo denunciado era falso,\u00a0<b>pero luego Espinoza reconoci\u00f3 que s\u00ed concurri\u00f3 a su domicilio pero s\u00f3lo para dialogar por \u2018cuestiones de trabajo\u2019\u00a0<\/b>(habiendo comenzado a trabajar desde hac\u00eda pocos d\u00edas en su municipio), y que se trat\u00f3 s\u00f3lo de una oportunidad no recordando cu\u00e1ndo (y no 3, como asegur\u00f3 la v\u00edctima)\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cDeviene significativo incluso, la infundada hip\u00f3tesis de la defensa de explicar, conoci\u00e9ndose el resultado de las antenas telef\u00f3nicas que se activaron demostrando la ubicaci\u00f3n f\u00edsica del imputado en la zona donde se ubica el departamento de la v\u00edctima (&#8230;) . M\u00e1s all\u00e1 de las inconsistencias, en definitiva, el descargo que introduce el imputado no resulta suficiente para desligarlo de la responsabilidad que aqu\u00ed le cabe prima facie por los hechos 1 y 2 atribuidos, frente a la contundencia de la prueba recabada, y no puede ser vista m\u00e1s que como un<b>\u00a0falso e inveros\u00edmil efugio enarbolado en pos de brindar alguna explicaci\u00f3n frente a la comprometida situaci\u00f3n que enfrenta\u201d,\u00a0<\/b>se\u00f1al\u00f3 el fallo.<\/p>\n<p data-mrf-recirculation=\"Links inline\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2960\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51-300x200.jpg 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51-1024x683.jpg 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51-768x512.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51-1536x1025.jpg 1536w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/05\/51.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Seg\u00fan la jueza, por el contrario \u201cluce m\u00e1s acertado y natural pensar que la damnificada padeci\u00f3 inesperadamente los tocamientos imp\u00fadicos sobre su cuerpo sin su consentimiento por parte de quien se trataba su jefe en ese entonces y de una persona p\u00fablica, y de la manera que pudo denunci\u00f3 lo ocurrido, con angustia y perturbada producto del accionar sorpresivo y deliberado del imputado de avasallar su libertad sexual aprovechando su autoridad, que la coloca naturalmente por su rol en una situaci\u00f3n de desventaja\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La resoluci\u00f3n fue dictada la semana pasada y\u00a0<b>se descuenta que la defensa apelar\u00e1 la decisi\u00f3n para revocar el procesamiento.<\/b><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Procesaron por abuso sexual al intendente de La Matanza Fernando Espinoza. La denuncia, hecha en 2021, fue radicada por una joven que trabajaba como secretaria privada del jefe comunal. En la causa, el intendente neg\u00f3 los hechos, pero la jueza no le crey\u00f3. Fernando Espinoza, intendente de La Matanza Una jueza proces\u00f3 por abuso sexual &hellip;<\/p>\n","protected":false},"author":2,"featured_media":2961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,33],"tags":[783,782,784],"class_list":["post-2959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justicia","category-nacionales","tag-fernando-espinozasiempre-te-tuve-ganas","tag-la-matanza","tag-va-a-estar-todo-bien"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2959"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2959\/revisions"}],"predecessor-version":[{"id":2962,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2959\/revisions\/2962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2961"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}