{"id":5393,"date":"2024-12-18T11:39:35","date_gmt":"2024-12-18T10:39:35","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=5393"},"modified":"2024-12-18T11:39:35","modified_gmt":"2024-12-18T10:39:35","slug":"se-viene-una-nueva-edicion-del-maraton-mirador-de-tafi","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2024\/12\/18\/se-viene-una-nueva-edicion-del-maraton-mirador-de-tafi\/","title":{"rendered":"Se viene una nueva edici\u00f3n del \u00abMarat\u00f3n Mirador de Taf\u00ed\u00bb"},"content":{"rendered":"<p class=\"title\">\u00a1Confirmado!\u00a0El evento organizado por la Asociaci\u00f3n Bancaria anunci\u00f3 la fecha de la pr\u00f3xima cita deportiva.<\/p>\n<div class=\"at-vc\">\n<div id=\"vsmcontent\" class=\"content vsmcontent\">\n<p><strong>El pr\u00f3ximo 8 de febrero se llevar\u00e1 a cabo la sexta edici\u00f3n del Marat\u00f3n Mirador de Taf\u00ed.<\/strong> El evento deportivo es organizado por la <strong>Asociaci\u00f3n Bancaria<\/strong>. Como todos los a\u00f1os, se busca poder contribuir a la sociedad, en esta edici\u00f3n\u00a0<span class=\"highlight\">lo recaudado ser\u00e1 destinado a la <strong>construcci\u00f3n de un helipuerto en Taf\u00ed del Valle<\/strong><\/span><strong>.\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5395\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-198x300.jpg 198w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-676x1024.jpg 676w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-768x1163.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-1014x1536.jpg 1014w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-1353x2048.jpg 1353w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_131729-scaled.jpg 1691w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/p>\n<figure class=\"vsmwidget widget-type-instagram\" contenteditable=\"false\"><\/figure>\n<h2>SEXTA EDICI\u00d3N DEL \u00abMarat\u00f3n Mirador de Taf\u00ed\u00bb<\/h2>\n<p>Desde la comisi\u00f3n organizadora confirmaron que la carrera tendr\u00e1 dos categor\u00edas: una de 3k y otra de 10k. Adem\u00e1s de poder vivir una jornada a puro deporte, se vivir\u00e1 un show de m\u00fasica en vivo y muchas sorpresas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5396\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-142x300.jpg\" alt=\"\" width=\"142\" height=\"300\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-142x300.jpg 142w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-485x1024.jpg 485w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-768x1623.jpg 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-727x1536.jpg 727w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-969x2048.jpg 969w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/20240224_164253-scaled.jpg 1211w\" sizes=\"auto, (max-width: 142px) 100vw, 142px\" \/><\/p>\n<h2>Lo que dej\u00f3 la \u00faltima fecha<\/h2>\n<p>En la quinta edici\u00f3n participaron 2500 personas.<span class=\"highlight\">\u00a0Se logr\u00f3 recaudar $60 millones, lo obtenido se don\u00f3 a la Polic\u00eda de Taf\u00ed del Valle, para la construcci\u00f3n de un Centro de Monitoreo.<\/span>\u00a0En la edici\u00f3n del 2023 se compr\u00f3 un cami\u00f3n cisterna de 9.000 litros para los bomberos.<\/p>\n<figure class=\"vsmwidget widget-type-instagram\" contenteditable=\"false\"><iframe id=\"instagram-embed-1\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/C3v5D_suhkI\/embed\/captioned\/?cr=1&amp;v=14&amp;wp=540&amp;rd=https%3A%2F%2Fwww.enteratenoticias.com.ar&amp;rp=%2Factualidad%2Fconfirmado-se-viene-una-nueva-edicion-del-maraton-mirador-de-tafi%2F#%7B%22ci%22%3A1%2C%22os%22%3A270.09999999403954%2C%22ls%22%3A152.40000000596046%2C%22le%22%3A162.30000001192093%7D\" height=\"1140\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-1\" data-mce-fragment=\"1\"><\/iframe><\/figure>\n<\/div>\n<\/div>\n<section id=\"tags-content-19552\" class=\"tag-section\">\n<header class=\"tag-section-header\"><\/header>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Confirmado!\u00a0El evento organizado por la Asociaci\u00f3n Bancaria anunci\u00f3 la fecha de la pr\u00f3xima cita deportiva. El pr\u00f3ximo 8 de febrero se llevar\u00e1 a cabo la sexta edici\u00f3n del Marat\u00f3n Mirador de Taf\u00ed. El evento deportivo es organizado por la Asociaci\u00f3n Bancaria. Como todos los a\u00f1os, se busca poder contribuir a la sociedad, en esta edici\u00f3n\u00a0lo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":5397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,294,34],"tags":[544,1378,1004],"class_list":["post-5393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-futbol","category-locales","tag-bancaria","tag-maraton","tag-tafi-del-valle"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5393"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5393\/revisions"}],"predecessor-version":[{"id":5398,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5393\/revisions\/5398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5397"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}