{"id":5433,"date":"2024-12-19T12:50:19","date_gmt":"2024-12-19T11:50:19","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=5433"},"modified":"2024-12-19T12:51:27","modified_gmt":"2024-12-19T11:51:27","slug":"los-desafueros-suspensiones-y-expulsiones-de-legisladores-del-83-al-presente","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2024\/12\/19\/los-desafueros-suspensiones-y-expulsiones-de-legisladores-del-83-al-presente\/","title":{"rendered":"Los desafueros, suspensiones y expulsiones de legisladores del 83 al presente"},"content":{"rendered":"<div class=\"post-content\">\n<p>El caso de Edgardo Kueider vuelve a la palestra la cuesti\u00f3n de los fueros legislativos y, en este caso, la expulsi\u00f3n de los legisladores. Una recorrida por todos los casos que involucraron a diputados y senadores desde 1983 a la fecha. Solo dos legisladores fueron echados en ese tiempo. Lo del ahora exsenador nacional <strong>Edgardo Kueider rompi\u00f3 todos los moldes.\u00a0<\/strong><\/p>\n<p>Hasta ahora, hab\u00eda casos de legisladores desaforados y luego detenidos. Pero el entrerriano elev\u00f3 el nivel de atenci\u00f3n porque al haberle pasado lo que le pas\u00f3 en el exterior, donde los fueros legislativos no corren, exhibi\u00f3\u00a0<strong>por primera vez a un legislador nacional detenido en esa condici\u00f3n<\/strong>. No en la c\u00e1rcel, convengamos, pero s\u00ed al menos en esa condici\u00f3n in\u00e9dita para un legislador.<\/p>\n<\/div>\n<div class=\"contenido-post\">\n<p>La cuesti\u00f3n es que el caso del entrerriano, detenido en tierras guaran\u00edes con d\u00f3lares que no hab\u00eda declarado y expulsado luego en el Senado nacional, vuelve a poner en el candelero un tema que recurrentemente genera pol\u00e9mica en la pol\u00edtica argentina: los fueros legislativos. Y pese a que vuelve una y otra vez, son m\u00e1s los gestos ampulosos que se hacen en estas situaciones que medidas concretas las que se toman.<\/p>\n<p>En el paroxismo de la sobreactuaci\u00f3n, peri\u00f3dicamente se sugiere la eliminaci\u00f3n de ese privilegio, mostrando un inquietante desconocimiento de las normas, habida cuenta de que es la Constituci\u00f3n nacional la que lo establece, dicho lo cual, si se desea eliminarlos habr\u00e1 que reformar la Carta Magna. Dif\u00edcil que se animen.<\/p>\n<p>Son tres los art\u00edculos en los que se habla de los fueros, tan importantes son en el sistema constitucional. <strong>En el 68 se los presenta en sociedad, aclarando que \u201cninguno de los miembros del Congreso puede ser acusado, interrogado judicialmente, ni molestado por las opiniones o discursos que emita desempe\u00f1ando su mandato de legislador\u201d. Esto es, resulta claro que la norma no ampara a los legisladores que delinquen, sino que se circunscribe estrictamente a lo que digan u opinen durante sus mandatos.<\/strong><\/p>\n<p>Y en el art\u00edculo siguiente se establece otra aclaraci\u00f3n: \u201cNing\u00fan senador o diputado, desde el d\u00eda de su elecci\u00f3n hasta el de su cese, puede ser arrestado;\u00a0<strong>excepto el caso de ser sorprendido in fraganti<\/strong>\u00a0en la ejecuci\u00f3n de alg\u00fan crimen que merezca pena de muerte, infamante, u otra aflictiva; de lo que se dar\u00e1 cuenta a la C\u00e1mara respectiva con la informaci\u00f3n sumaria del hecho\u201d.<\/p>\n<p>En cuyo caso, amerita el tercer art\u00edculo en cuesti\u00f3n, el 70, que precisa que <strong>\u201ccuando se forme querella por escrito ante las justicias ordinarias contra cualquier senador o diputado, examinado el m\u00e9rito del sumario en juicio p\u00fablico, podr\u00e1 cada C\u00e1mara, con dos tercios de votos, suspender en sus funciones al acusado, y ponerlo a disposici\u00f3n del juez competente para su juzgamiento\u201d.<\/strong><\/p>\n<p>La Constituci\u00f3n es muy clara, pero as\u00ed y todo existe una ley nacional que rige los alcances de los fueros, pues ya se sabe que las interpretaciones constitucionales suelen ser demasiado amplias, por lo que en determinadas circunstancias se deben dar precisiones legales que no dejen lugar a dudas. Y as\u00ed llegamos a la Ley 25.320, que estableci\u00f3 un nuevo R\u00e9gimen de Inmunidades para legisladores, funcionarios y magistrados, sancionada el 8 de septiembre del a\u00f1o 2000 y promulgada por el Gobierno de\u00a0<strong>Fernando de la R\u00faa<\/strong> cuatro d\u00edas despu\u00e9s. Como se ve, hab\u00eda cierta prisa por poner en marcha esa norma pues hasta entonces la ley vigente amparaba a los legisladores a eludir a los jueces. \u00bfCu\u00e1l fue el disparador de entonces? Nada menos que los sobornos del Senado, menuda cuesti\u00f3n.<\/p>\n<p>En el pasado reciente se dio el caso de\u00a0<strong>Julio De Vido,\u00a0<\/strong>que desat\u00f3 una fiebre por \u201crenunciar a los fueros\u201d. Eran tiempos de Cambiemos, y en ese entonces pic\u00f3 en punta\u00a0<strong>Sergio Massa<\/strong>, quien entre otras cosas dijo que era mentira que no hubiera antecedentes, y cit\u00f3 el caso de\u00a0<strong>Eduardo Angeloz<\/strong>, que pudo renunciar a ese privilegio. Ese caso amerita una aclaraci\u00f3n. Sucedi\u00f3 en 1996, y como acabamos de ver por la reforma de la Ley de Fueros en el a\u00f1o 2000, hasta entonces los legisladores estaban blindados para toda acci\u00f3n judicial. Acusado en febrero de 1996 por el fiscal\u00a0<strong>Carlos Ferrer<\/strong>\u00a0por lo que se conoci\u00f3 popularmente como el <strong>\u201cmegaproceso del Banco Social\u201d, fue el propio exgobernador cordob\u00e9s, por entonces senador nacional, quien pidi\u00f3 al presidente del Senado,\u00a0Carlos Ruckauf, su desafuero para que la C\u00e1mara alta dispusiera \u201clas medidas que estime pertinente\u201d<\/strong>.<\/p>\n<p>En rigor, lo que hizo fue anticiparse al desafuero que requer\u00eda el reclamo judicial, pero entonces se gener\u00f3 una pol\u00e9mica en la C\u00e1mara alta. Como siempre, all\u00ed el bloque del PJ ten\u00eda la \u00faltima palabra por ser mayor\u00eda, aunque presentaba diferentes criterios, pero finalmente se le quitaron por completo los fueros para ser juzgado. Durante ese tiempo que se extendi\u00f3 varios meses, Angeloz debi\u00f3 dejar el Senado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-378602 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Angeloz.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Angeloz.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Angeloz-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p><strong>El caso Mar\u00eda Soledad<\/strong><\/p>\n<p>Tal vez hasta ahora el caso m\u00e1s recordado y contundente haya sido el del diputado nacional catamarque\u00f1o\u00a0<strong>Angel Luque<\/strong>\u00a0(PJ), a quien no le quitaron los fueros, sino que\u00a0<strong>directamente lo expulsaron de la C\u00e1mara baja<\/strong>, acusado de \u201cindignidad moral\u201d. Su hijo\u00a0<strong>Guillermo<\/strong>\u00a0era uno de los acusados del crimen de\u00a0<strong>Mar\u00eda Soledad Morales<\/strong>\u00a0ocurrido en 1990, y en el marco de un reportaje acus\u00f3 al juez de la causa,\u00a0<strong>Jos\u00e9 Luis Vengimiglia<\/strong>, de haber recibido 250 mil d\u00f3lares para encarcelar a su hijo. Pero eso no fue lo que sell\u00f3 su destino, sino el peculiar argumento de defensa que termin\u00f3 cost\u00e1ndole la carrera, al se\u00f1alar que ten\u00eda suficiente poder como para hacer desaparecer el cad\u00e1ver si su hijo hubiera sido el verdadero asesino.\u00a0<strong>La C\u00e1mara de Diputados lo expuls\u00f3 en 1991<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-378598 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Luque.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Luque.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Luque-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p>Ese caso fue utilizado como antecedente en 1999, cuando la C\u00e1mara de Diputados impidi\u00f3 la asunci\u00f3n de\u00a0<strong>Antonio Domingo Bussi<\/strong>, acusado por su participaci\u00f3n en la dictadura y tambi\u00e9n de haber ocultado una cuenta bancaria en Suiza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5434 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/BUSSI.jpg\" alt=\"\" width=\"640\" height=\"444\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/BUSSI.jpg 640w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2024\/12\/BUSSI-300x208.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Al que s\u00ed desaforaron de manera contundente los diputados fue al exsubcomisario\u00a0<strong>Luis Patti<\/strong>. Fue el 24 de abril de 2008, cuando tras un debate de m\u00e1s de siete horas se aprob\u00f3 en Diputados su desafuero solicitado por el juez\u00a0<strong>Alberto Su\u00e1rez Araujo<\/strong>\u00a0en el marco de una causa por delitos de lesa humanidad. En rigor, Patti era diputado electo, pero no le hab\u00edan permitido jurar, por lo que algunos sosten\u00edan que para poder desaforarlo deb\u00edan primero autorizar su juramento. Convengamos que el art\u00edculo 69 de la Constituci\u00f3n indica que los fueros corren para el legislador desde el d\u00eda que es electo (recordemos la parte que dice: \u201cning\u00fan senador o diputado, desde el d\u00eda de su elecci\u00f3n hasta el de su cese, puede ser arrestado\u201d).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-378599 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Patti.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Patti.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Luis-Patti-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p>El desafuero de Patti fue aprobado por 196 votos a favor, 9 en contra y 11 abstenciones.<\/p>\n<p>Tampoco pudo sentarse nunca en su banca el exgobernador\u00a0<strong>Ra\u00fal \u201cTato\u201d Romero Feris<\/strong>, elegido senador nacional por Corrientes, al que directamente la C\u00e1mara Nacional Electoral impidi\u00f3 asumir en 2003 por \u201cincompatibilidad \u00e9tica\u201d, a ra\u00edz de causas judiciales pendientes. Romero Feris hab\u00eda sido elegido senador nacional por el Partido Nuevo, pero su pliego no fue aprobado junto a los correspondientes a la mayor\u00eda de los nuevos miembros de la C\u00e1mara alta por demoras en la comunicaci\u00f3n de la justicia electoral correntina.<\/p>\n<p>Quien impugn\u00f3 entonces al<strong> \u201cTato\u201d<\/strong> fue quien m\u00e1s adelante ser\u00eda diputada nacional peronista\u00a0<strong>Araceli M\u00e9ndez de Ferreyra<\/strong>, por considerar que estaba \u201cinhabilitado moral y \u00e9ticamente\u201d para ocupar una banca.<\/p>\n<p>Romero Feris hab\u00eda sido condenado por presuntos hechos de corrupci\u00f3n administrativa cometidos desde los cargos p\u00fablicos que ejerci\u00f3 en Corrientes.<\/p>\n<p>En 1995 el diputado justicialista\u00a0<strong>Eduardo Varela Cid<\/strong>\u00a0no fue desaforado sino suspendido hasta el final de su mandato por \u201cdes\u00f3rdenes de conducta\u201d tras haber admitido haber requerido colaboraciones a empresarios postales, a trav\u00e9s de un bono, en el momento en que se opon\u00eda a la controvertida ley de Correos. Durante el lapso que dur\u00f3 la suspensi\u00f3n, perdi\u00f3 fueros, banca y dieta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-378600 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Varela-Cid.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Varela-Cid.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Eduardo-Varela-Cid-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p>Otro caso sucedi\u00f3 en 2002 con la diputada peronista\u00a0<strong>Norma Ancari de Godoy<\/strong>, quien fue denunciada por el programa de televisi\u00f3n \u201cPunto Doc\u201d, que exhibi\u00f3 im\u00e1genes captadas con una c\u00e1mara oculta que mostraban a la legisladora amenazando a un productor de ese env\u00edo televisivo con que iba a \u201cmatarlo a itakazos\u201d. Esa investigaci\u00f3n period\u00edstica versaba sobre el destino de ATN a fundaciones de discapacitados. Asediada en el Congreso, la diputada evit\u00f3 su expulsi\u00f3n renunciando el 9 de abril de 2002, cuando ya la Comisi\u00f3n de Asuntos Constitucionales, que presid\u00eda\u00a0<strong>Juan Manuel Urtubey<\/strong>, hab\u00eda aconsejado su expulsi\u00f3n \u201cpor des\u00f3rdenes de conducta\u201d.<\/p>\n<p>En marzo de 2003, la oposici\u00f3n pidi\u00f3 la expulsi\u00f3n del senador\u00a0<strong>Luis Barrionuevo<\/strong>, por su responsabilidad en los frustrados comicios catamarque\u00f1os. En esa oportunidad, la entonces senadora\u00a0<strong>Diana Conti<\/strong>\u00a0advirti\u00f3 que el tema no pod\u00eda quedar en simples expresiones de repudio del Cuerpo, sino que el mismo deb\u00eda \u201cvotar el desafuero de Barrionuevo\u201d, quien era acusado de haber mandado a quemar urnas.<\/p>\n<p>El l\u00edder gastron\u00f3mico hab\u00eda sido impedido de participar en esos comicios porque la Constituci\u00f3n provincial le exig\u00eda un tiempo de residencia en la provincia que \u00e9l no ten\u00eda para poder ser candidato. Lejos estuvo de resignarse a aceptar la decisi\u00f3n, e insisti\u00f3 hasta el final, presentando recursos que llegaron hasta la Corte Suprema. Las autoridades locales del Frente C\u00edvico sab\u00edan que Barrionuevo ser\u00eda un adversario temible en las urnas y realizaron la elecci\u00f3n tal cual lo previsto, sin dar lugar a una postergaci\u00f3n, ante lo cual el senador justicialista se consider\u00f3 proscripto y actu\u00f3 en consecuencia&#8230;<\/p>\n<p>Lo que sigui\u00f3 fue una elecci\u00f3n escandalosa, en la que los partidarios de Barrionuevo prohibieron el acto electoral en algunas escuelas y hasta quemaron urnas.<\/p>\n<p>La Comisi\u00f3n de Asuntos Constitucionales de la C\u00e1mara alta, que presid\u00eda\u00a0<strong>Cristina Fern\u00e1ndez de Kirchner<\/strong>\u00a0-senadora a\u00fan en el llano- termin\u00f3 emitiendo un dictamen en el que recomendaba excluir del cuerpo a Barrionuevo bajo el cargo de \u201cinhabilidad moral\u201d.<\/p>\n<p>Sin embargo, al promediar la noche del 27 de marzo de 2003 el peronismo termin\u00f3 salv\u00e1ndolo, aunque vot\u00f3 dividido, ya que ocho senadores del PJ votaron junto a la oposici\u00f3n y los provinciales para expulsarlo. Los votos en ese sentido fueron 37, diez m\u00e1s que los que optaron por salvarlo, pero seis menos que los necesarios para los dos tercios que hubieran dejado al sindicalista fuera del Senado. \u201cSe perdi\u00f3 una oportunidad muy grande. Si el Senado anterior es recordado como el de la Banelco y el de (el senador nacional\u00a0<strong>Emilio) Cantarero<\/strong>, \u00e9ste ser\u00e1 recordado como el del esc\u00e1ndalo Barrionuevo. Vi a muchos senadores que le temen, otros que privilegiaron el esp\u00edritu del cuerpo; en mi caso, no le tengo miedo. Lo m\u00e1s grave de la decisi\u00f3n de mis pares es que Luis Barrionuevo se llev\u00f3 puesto el Senado. Sucede que en Argentina hay una corporaci\u00f3n pol\u00edtica y ese es el drama central de esta democracia\u201d, se quej\u00f3 entonces Cristina Kirchner.<\/p>\n<p>Un caso menos recordado pero digno de ser muy tenido en cuenta fue el del senador puntano\u00a0<strong>Ra\u00fal Ochoa<\/strong>, condenado en 2005 a dos a\u00f1os de prisi\u00f3n en suspenso y 9 de inhabilitaci\u00f3n para ejercer cargos p\u00fablicos\u00a0<strong>por haber votado dos veces en una elecci\u00f3n<\/strong>. La C\u00e1mara alta, m\u00e1s propensa a proteger a sus miembros, no procedi\u00f3 a su desafuero y lo dej\u00f3 concluir su mandato, a fines de ese a\u00f1o. Es tambi\u00e9n lo que hizo con el expresidente\u00a0<strong>Carlos Menem<\/strong>, condenado por tr\u00e1fico de armas, aunque sin condena firme, que muri\u00f3 cumpliendo su tercer a\u00f1o como senador. La re-re que no pudo conseguir como presidente, y que le permiti\u00f3 mantenerse en libertad.<\/p>\n<p><strong>Los sobornos del Senado<\/strong><\/p>\n<p>El hecho conmocionante que comenz\u00f3 a edificar el camino de salida del Gobierno de la Alianza fue un caso de corrupci\u00f3n que estall\u00f3 en mayo del a\u00f1o 2000, tras la sanci\u00f3n de la Ley 25.250, conocida como Ley de Reforma Laboral, y que por el esc\u00e1ndalo pas\u00f3 a denominarse Ley Banelco. Se investig\u00f3 all\u00ed si el gobierno de Fernando de la R\u00faa hizo pagos a senadores del PJ para que votaran a favor de esa ley.<\/p>\n<p>El juez a cargo del caso era\u00a0<strong>Carlos Liporaci<\/strong>, quien pidi\u00f3 el desafuero de once senadores:\u00a0<strong>Ricardo Branda, Remo Costanzo, Ram\u00f3n Ortega, Angel Pardo, Eduardo Bauz\u00e1, Emilio Cantarero y Alberto Tell, del PJ; y Javier Meneghini, Ra\u00fal Galv\u00e1n\u00a0<\/strong>y\u00a0<strong>Alcides L\u00f3pez<\/strong>, de la UCR. No fueron concedidos y poco despu\u00e9s se modific\u00f3 la ley de fueros para que lo que sucedi\u00f3 entonces no volviera a pasar.<\/p>\n<p><strong>El caso De Vido<\/strong><\/p>\n<p>El 19 de enero de 2016,\u00a0<strong>Elisa Carri\u00f3<\/strong>\u00a0pidi\u00f3 a la Justicia que se investigara al exministro de Planificaci\u00f3n Federal y entonces diputado nacional\u00a0<strong>Julio<\/strong>\u00a0<strong>De Vido\u00a0<\/strong>por el supuesto delito de corrupci\u00f3n, a ra\u00edz de la confesi\u00f3n de un exdirector de Petrobras en Brasil,\u00a0<strong>N\u00e9stor Cerver\u00f3<\/strong>, que aseguraba haber recibido en 2006 coimas por la venta de la empresa de transmisi\u00f3n de energ\u00eda Transener, adquirida por Petrobras. El exdirector del \u00e1rea internacional de Petrobras hab\u00eda involucrado directamente a De Vido.<\/p>\n<p>A partir de ah\u00ed, De Vido comenz\u00f3 a acumular causas y en una, us\u00f3 sus fueros para impedir el allanamiento de un departamento de su propiedad sito en la Avenida del Libertador 2275. La medida hab\u00eda sido dispuesta por el juez federal\u00a0<strong>Luis Rodr\u00edguez<\/strong>, en el marco de una investigaci\u00f3n por supuesto enriquecimiento il\u00edcito entre 2003 y 2007.<\/p>\n<p>El 23 de junio de 2016 la C\u00e1mara baja autoriz\u00f3 que pudieran allanarlo, por 137 votos positivos, 49 negativos y una sola abstenci\u00f3n -la del propio De Vido-.<\/p>\n<p>En julio de 2017 estall\u00f3 otro esc\u00e1ndalo judicial que involucraba a De Vido por la supuesta apropiaci\u00f3n de recursos p\u00fablicos en Yacimientos Carbon\u00edferos Fiscales de R\u00edo Turbio. El fiscal\u00a0<strong>Carlos Stornelli<\/strong>\u00a0pidi\u00f3 la detenci\u00f3n de Julio De Vido,\u00a0<strong>Roberto Baratta<\/strong>\u00a0y dos decenas de otras personas por esa causa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-378601 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Julio-de-Vido-diputado.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Julio-de-Vido-diputado.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2024\/12\/Julio-de-Vido-diputado-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p>El 26 de julio de 2017 De Vido zaf\u00f3 de la expulsi\u00f3n. Con 138 votos afirmativos y 95 en contra, faltaron 20 votos para los dos tercios. El argumento para expulsarlo era<strong> \u201cinhabilidad moral\u201d.<\/strong><\/p>\n<p>Cinco d\u00edas despu\u00e9s de que la C\u00e1mara de Diputados \u201cblindara\u201d a Julio De Vido, la Sala II de la C\u00e1mara Federal pidi\u00f3 al juez Luis Rodr\u00edguez un informe sobre la decisi\u00f3n por la que hab\u00eda rechazado la solicitud del fiscal Stornelli de detener al exministro, cuya suerte parec\u00eda oscurecerse cada vez m\u00e1s pues mientras comenzaba a preocuparlo la causa Odebrecht, deten\u00edan en Chapadmalal a su cu\u00f1ado\u00a0<strong>Claudio Minnicelli<\/strong>, pr\u00f3fugo desde hac\u00eda 9 meses en la causa denominada \u201cmafia de los contenedores\u201d.<\/p>\n<p>El juez cambi\u00f3 su actitud y lo cit\u00f3 a indagaoria para el 28 de noviembre y le prohibi\u00f3 salir del pa\u00eds. Al d\u00eda siguiente, el fiscal de C\u00e1mara\u00a0<strong>Germ\u00e1n Moldes<\/strong>\u00a0pidi\u00f3 su inmediata detenci\u00f3n en un dictamen muy duro en el que advert\u00eda que en su condici\u00f3n de diputado nacional De Vido ten\u00eda \u201ccapacidad de incidencia y negociaci\u00f3n\u201d, por lo que ped\u00eda su desafuero \u201ccon la premura y firmeza del caso\u201d.<\/p>\n<p>El 19 de octubre De Vido sum\u00f3 otro frente de tormenta cuando el juez Claudio Bonadio dispuso tambi\u00e9n su desafuero y detenci\u00f3n por supuesto fraude en la compra millonaria de gas licuado. Al d\u00eda siguiente de las elecciones legislativas que le dieron a Cambiemos una resonante victoria, y con todas las cartas ya decididamente en contra, Julio De Vido pidi\u00f3 licencia como diputado y renunci\u00f3 paralelamente a su cargo como presidente de la Comisi\u00f3n de Energ\u00eda y Combustibles.<\/p>\n<p>El 25 de octubre de 2017 -sin la presencia del bloque FpV-PJ, que resolvi\u00f3 no asistir- se vot\u00f3 su desafuero y suspensi\u00f3n, con 176 votos a favor y una sola abstenci\u00f3n. De Vido fue r\u00e1pidamente detenido y su banca estuvo vac\u00eda hasta el final de su mandato. Esa era la estrategia que desde el Pro y la UCR hab\u00edan impulsado originalmente para el caso Kueider.<\/p>\n<p>Luego del caso De Vido, fue el turno del radicalismo cuando una jueza federal de Resistencia pidi\u00f3 el desafuero y detenci\u00f3n de la diputada nacional\u00a0<strong>A\u00edda Ayala,\u00a0<\/strong>en el marco de una causa por supuesto lavado de dinero, negociaciones incompatibles con la funci\u00f3n p\u00fablica y enriquecimiento il\u00edcito. \u00a0Fue en abril de 2018, y la legisladora radical denunci\u00f3 \u201cuna maniobra pol\u00edtica\u201d. Si bien en principio el oficialismo se hab\u00eda resignado a entregar su cabeza, termin\u00f3 ampar\u00e1ndola en la Comisi\u00f3n de Asuntos Constitucionales y el caso no lleg\u00f3 nunca al recinto.<\/p>\n<p><strong>La situaci\u00f3n de CFK<\/strong><\/p>\n<p>Tras dos a\u00f1os en el llano, la expresidenta\u00a0<strong>Cristina Kirchner<\/strong>\u00a0fue electa senadora en octubre de 2017. Impulsora de denuncias en su contra,\u00a0<strong>Margarita Stolbizer\u00a0<\/strong>anticip\u00f3 que se presentar\u00eda ante la Justicia para pedirles a los jueces que llevaran adelante causas donde la flamante senadora electa estuviera procesada, pidieran el desafuero. Y antes que asumiera, CFK ya ten\u00eda un pedido de desafuero y detenci\u00f3n por parte del juez\u00a0<strong>Claudio Bonadio\u00a0<\/strong>en la causa del Memorandum con Ir\u00e1n.<\/p>\n<p>Desde Cambiemos se aclar\u00f3 que no pod\u00edan impulsar una sesi\u00f3n para tratar el desafuero en extraordinarias, mientras\u00a0<strong>Miguel Pichetto,\u00a0<\/strong>presidente del bloque Justicialista, consideraba que no correspond\u00eda el pedido de prisi\u00f3n preventiva, ni pensaban avalarlo al no existir una condena definitiva.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11377 size-full\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2020\/02\/ib_039_487.jpg\" alt=\"\" width=\"657\" height=\"407\" \/><\/p>\n<p>De eso se habl\u00f3 todo ese verano y cuando se reanud\u00f3 el per\u00edodo ordinario en 2018 y se constituy\u00f3 Asuntos Constitucionales, la comisi\u00f3n que deb\u00eda tratar el tema, a fines de marzo fueron liberados\u00a0<strong>Carlos Zannini\u00a0<\/strong>y\u00a0<strong>Luis D\u2019El\u00eda,\u00a0<\/strong>detenidos en el marco de esa causa, con lo que virtualmente qued\u00f3 sin efecto el pedido de desafuero y arresto formulado por el juez Bonadio.<\/p>\n<p>As\u00ed y todo el tema se reactiv\u00f3 cuando Bonadio insisti\u00f3 con su pedido de desafuero, y Cambiemos convoc\u00f3 a debatirlo el 20 de noviembre de 2018, pero la sesi\u00f3n no tuvo qu\u00f3rum.<\/p>\n<p><strong>El \u201cdiputeta\u201d<\/strong><\/p>\n<p>El caso m\u00e1s curioso fue sin dudas el que tuvo lugar en plena pandemia, cuando las sesiones se hac\u00edan por videoconferencias. Fue el 24 de septiembre de 2020, cuando en plena sesi\u00f3n un diputado conectado en forma virtual protagoniz\u00f3 una escena \u00edntima con su pareja, que qued\u00f3 a la vista porque su c\u00e1mara estaba encendida.<\/p>\n<p>Pas\u00f3 con el salte\u00f1o del Frente de Todos\u00a0<strong>Juan Ameri,\u00a0<\/strong>quien fue inmediatamente suspendido por el presidente de la C\u00e1mara, Sergio Massa, quien pidi\u00f3 la aplicaci\u00f3n del art\u00edculo 188 del reglamento, y en paralelo la conformaci\u00f3n de una comisi\u00f3n de cinco miembros para que determinaran si correspond\u00eda la expulsi\u00f3n para ese legislador. Al cabo de la sesi\u00f3n, Ameri hab\u00eda presentado la renuncia como diputado nacional.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/v5ysPzZthGA?si=YG2MBMLZKQdmE1yD\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>Los casos pol\u00e9micos desde la recuperaci\u00f3n democr\u00e1tica<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td><strong>A\u00f1o<\/strong><\/td>\n<td><strong>Nombre<\/strong><\/td>\n<td><strong>Qu\u00e9 pas\u00f3<\/strong><\/td>\n<\/tr>\n<tr>\n<td>1991<\/td>\n<td>Angel Luque<\/td>\n<td><em><strong>Expulsado<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>1995<\/td>\n<td>Eduardo Varela Cid<\/td>\n<td><em><strong>Suspendido<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>1996<\/td>\n<td>Eduardo Angeloz<\/td>\n<td><em><strong>Pidi\u00f3 su propio desafuero<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>1999<\/td>\n<td>Antonio Bussi<\/td>\n<td><em><strong>No pudo asumir<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2000<\/td>\n<td>Sobornos del Senado<\/td>\n<td><em><strong>Nada<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2002<\/td>\n<td>Norma Godoy<\/td>\n<td><em><strong>Renunci\u00f3<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2003<\/td>\n<td>Ra\u00fal Romero Feris<\/td>\n<td><em><strong>No pudo asumir<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2003<\/td>\n<td>Luis Barrionuevo<\/td>\n<td><em><strong>No alcanzaron los votos para echarlo<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2005<\/td>\n<td>Luis Patti<\/td>\n<td><em><strong>Se aprob\u00f3 su desafuero y no asumi\u00f3<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2005<\/td>\n<td>Ra\u00fal Ochoa<\/td>\n<td><em><strong>No se trat\u00f3<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2017<\/td>\n<td>Julio De Vido<\/td>\n<td><em><strong>Se aprob\u00f3 su desafuero y lo suspendieron<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2018<\/td>\n<td>Cristina Kirchner<\/td>\n<td><em><strong>No se trat\u00f3<\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td>2020<\/td>\n<td>Juan Ameri<\/td>\n<td><em><strong>Renunci\u00f3<\/strong><\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-size: 8pt;\"><strong>Por Jos\u00e9 Angel Di Mauro<\/strong><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El caso de Edgardo Kueider vuelve a la palestra la cuesti\u00f3n de los fueros legislativos y, en este caso, la expulsi\u00f3n de los legisladores. Una recorrida por todos los casos que involucraron a diputados y senadores desde 1983 a la fecha. Solo dos legisladores fueron echados en ese tiempo. Lo del ahora exsenador nacional Edgardo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":5435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,25],"tags":[410],"class_list":["post-5433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-politica","tag-congreso-de-la-nacion"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5433"}],"version-history":[{"count":2,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5433\/revisions"}],"predecessor-version":[{"id":5437,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5433\/revisions\/5437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5435"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}