{"id":6098,"date":"2025-03-02T14:29:57","date_gmt":"2025-03-02T13:29:57","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=6098"},"modified":"2025-03-02T14:29:57","modified_gmt":"2025-03-02T13:29:57","slug":"la-hoja-de-ruta-de-la-intendenta-rossana-chahla-para-este-2025","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2025\/03\/02\/la-hoja-de-ruta-de-la-intendenta-rossana-chahla-para-este-2025\/","title":{"rendered":"La hoja de ruta de la intendenta Rossana Chahla para este 2025"},"content":{"rendered":"<div class=\"td-post-header td-pb-padding-side\">\n<header>\n<p class=\"entry-title\"><span style=\"font-size: 12pt;\">La jefa municipal realiz\u00f3 una serie de anuncios en su discurso de Apertura de Sesiones Ordinarias del Concejo Deliberante capitalino. Destac\u00f3 la importancia de \u201csostener la obra p\u00fablica\u201d y de contar con \u201cun Estado presente y eficiente\u201d. Los renovados desaf\u00edos para el segundo a\u00f1o de gesti\u00f3n. <\/span>Al presidir la ceremonia de apertura del 120\u00b0 Per\u00edodo de Sesiones Ordinarias del Concejo Deliberante de San Miguel de Tucum\u00e1n, la intendenta Rossana Chahla enumer\u00f3 los principales desaf\u00edos y proyectos que marcar\u00e1n la agenda de trabajo 2025 para la actual gesti\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6100 size-large\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-1024x683.webp\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-1024x683.webp 1024w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-300x200.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-768x512.webp 768w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-1536x1024.webp 1536w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/03\/multimedia.grande.85ad2156f7184f4d.Z3JhbmRlLndlYnA-2048x1365.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<\/header>\n<\/div>\n<div class=\"td-post-content td-pb-padding-side\">\n<div class=\"code-block code-block-5\">\n<div class=\"td-all-devices\"><\/div>\n<\/div>\n<p><span style=\"font-size: 14pt;\"><strong>Los principales anuncios, que abarcan diferentes \u00e1reas, fueron los siguientes:<\/strong><\/span><\/p>\n<p><strong>Seguridad Ciudadana<\/strong><\/p>\n<p>En su mensaje anual ante el Concejo, la intendenta Chahla confirm\u00f3 que la Seguridad Ciudadana ser\u00e1 el eje principal en la agenda 2025. \u201cHemos articulado en una Subsecretar\u00eda, Defensa Civil, la Patrulla de Protecci\u00f3n Ciudadana (PPC) y el Centro de Monitoreo Municipal (COMM). Este equipo tendr\u00e1 la misi\u00f3n de dise\u00f1ar, coordinar y ejecutar pol\u00edticas de prevenci\u00f3n en seguridad, adem\u00e1s de mejorar nuestra capacidad de respuesta en articulaci\u00f3n con el Ministerio de Seguridad de la provincia\u201d, explic\u00f3. Agreg\u00f3 que, desde el Centro de Operaciones y Monitoreo Municipal, durante 2024 se comenz\u00f3 a trabajar para mejorar el servicio de vigilancia. En ese sentido, resalt\u00f3 que el Municipio est\u00e1 realizando \u201cuna inversi\u00f3n significativa en videovigilancia y duplicando el n\u00famero de c\u00e1maras de seguridad que tenemos en la actualidad, para llegar a 500\u201d.<\/p>\n<p><strong>Innovaci\u00f3n Tecnol\u00f3gica<\/strong><\/p>\n<p>Uno de los principales desaf\u00edos que plante\u00f3 la intendenta para su gesti\u00f3n en 2025 es reforzar las pol\u00edticas en materia de innovaci\u00f3n tecnol\u00f3gica. En ese sentido, anunci\u00f3 el lanzamiento del Plan de Transformaci\u00f3n Digital (TRADI) que tiene como objetivo eliminar burocracias innecesarias y promover la despapelizaci\u00f3n de todos los procesos administrativos. Adem\u00e1s, inform\u00f3 que ya est\u00e1 disponible la app CIUDAD SMT, la aplicaci\u00f3n desarrollada por el Municipio junto al Banco Macro, para que los vecinos puedan instalarla gratuitamente en sus dispositivos. \u201cA trav\u00e9s de CIUDAD SMT, los vecinos podr\u00e1n notificarnos de forma georeferenciada sobre baches, \u00e1rboles ca\u00eddos, alumbrado p\u00fablico averiado o \u00e1rboles que necesitan poda, entre otras problem\u00e1ticas. Adem\u00e1s, podr\u00e1n inscribirse en actividades y eventos municipales, solicitar turnos en oficinas municipales y participar activamente en consultas p\u00fablicas\u201d, inform\u00f3.<\/p>\n<p>Tambi\u00e9n indic\u00f3 que \u201cpara lograr una comunicaci\u00f3n a\u00fan m\u00e1s cercana y efectiva, la ciudad contar\u00e1 con \u2018Miguelito\u2019, el nuevo chat de la Municipalidad que estar\u00e1 disponible para asesorar, responder consultas, enviar notificaciones y acompa\u00f1ar a nuestros vecinos en la realizaci\u00f3n de sus tr\u00e1mites\u201d.<\/p>\n<p><strong>Obras P\u00fablicas<\/strong><\/p>\n<p>En su discurso, Chahla ratific\u00f3 que otro de los pilares de su gesti\u00f3n en 2025 ser\u00e1n las obras p\u00fablicas para los vecinos. \u201cEscuchamos que se dice no a la obra p\u00fablica, mientras nosotros le decimos s\u00ed a la obra p\u00fablica. No queremos la obra p\u00fablica que beneficia a unos pocos de siempre y es la obra de la corrupci\u00f3n y de los negociados sino la obra p\u00fablica que mejora la calidad de vida de nuestra gente\u201d, plante\u00f3.<\/p>\n<p>Entres los principales proyectos para 2025, la intendenta anunci\u00f3 la obra de recuperaci\u00f3n y refuncionalizaci\u00f3n del Mercado de la Ciudad, en avenida Sarmiento al 1200, que est\u00e1 en proceso de licitaci\u00f3n p\u00fablica. Agreg\u00f3 que, paralelamente, se avanzar\u00e1 con la revalorizaci\u00f3n de la emblem\u00e1tica Plazoleta Mitre y su entorno. Por otro lado, anticip\u00f3 que se trabaja en la recuperaci\u00f3n del Camping Municipal para que sea \u201cun renovado espacio de recreaci\u00f3n para las familias\u201d. Y anunci\u00f3: \u201cImpulsamos un concurso abierto para que los vecinos puedan elegir el mejor proyecto para la construcci\u00f3n y concesi\u00f3n de la nueva Confiter\u00eda del Lago, un espacio emblem\u00e1tico que revitalizar\u00e1 el Parque 9 de Julio y lo convertir\u00e1 en un nuevo punto de encuentro para todos\u201d.<\/p>\n<p>Chahla indic\u00f3 que en 2025 se continuar\u00e1 adelante con un programa para la revalorizaci\u00f3n de 28 plazas en distintos puntos de la ciudad, que es uno de los compromisos asumidos para los segundos 180 d\u00edas de gesti\u00f3n. \u201cEsto significa que en poco m\u00e1s de un a\u00f1o, habremos logrado poner en condiciones 50 plazas de la ciudad. Con esta proyecci\u00f3n, vamos a recuperar el<\/p>\n<p>50% de nuestras plazas en el segundo a\u00f1o de gesti\u00f3n\u201d, subray\u00f3. La intendenta precis\u00f3 que \u201centre las plazas proyectadas para su renovaci\u00f3n integral se destaca la Plaza Urquiza, donde se iniciar\u00e1 un proceso de participaci\u00f3n ciudadana, para que sean los propios vecinos quienes elijan c\u00f3mo ser\u00e1 la plaza que queremos\u201d.<\/p>\n<p>Por otro lado, inform\u00f3 que en los pr\u00f3ximos meses continuar\u00e1 adelante el plan de recuperaci\u00f3n integral del pavimento en 280 cuadras distribuidas en 7 sectores de la ciudad, con la ejecuci\u00f3n de 60 cuadras de pavimento articulado y 44 cuadras de pavimento lineal en avenidas. Las tareas incluir\u00e1n \u201cla renovaci\u00f3n completa de la Avenida Mitre y la mejora de tramos en Avenida Roca y Adolfo de la Vega\u201d. La intendenta resalt\u00f3 que \u201cel pavimento interbarrial facilitar\u00e1 la conexi\u00f3n entre sectores actualmente desconectados, optimizando la accesibilidad y la integraci\u00f3n urbana\u201d.<\/p>\n<p><strong>Escuela Ambiental Municipal<\/strong><\/p>\n<p>\u201cVamos a inaugurar la primera sede central de la Escuela Ambiental Municipal en la calle San Mart\u00edn y su Campus en calle Lamadrid al 3700, abierta tanto a establecimientos p\u00fablicos como privados y a las familias los fines de semana\u201d, anunci\u00f3 la intendenta. Dijo que ese espacio contar\u00e1 con salas de cine para cortos ambientales, aulas para talleres con realidad virtual.<\/p>\n<p><strong>Escuela de Manejo<\/strong><\/p>\n<p>La intendenta remarc\u00f3 que se trabajar\u00e1 para mejorar la seguridad vial. \u201cEnviaremos prontamente a este Concejo un proyecto de ordenanza para que nadie compre una moto sin aprobar el curso de la Escuela de Manejo que estamos creando\u201d, anunci\u00f3. Explic\u00f3 que, adem\u00e1s, \u201cla obtenci\u00f3n del primer carnet ser\u00e1 m\u00e1s rigurosa, ya que requerir\u00e1 la aprobaci\u00f3n del curso de manejo\u201d. Y avis\u00f3: \u201cSeremos inflexibles respecto a las multas y el secuestro de las motos cuando no utilicen el casco, al igual que cuando no utilicen cintur\u00f3n de seguridad\u201d. Tambi\u00e9n inform\u00f3 que ya se cursaron notas de advertencia a las empresas de mensajer\u00eda y cadeter\u00eda sobre las sanciones que recibir\u00e1n cuando no cumplan con las normas de tr\u00e1nsito y seguridad vial.<\/p>\n<p><strong>Iluminaci\u00f3n y sem\u00e1foros<\/strong><\/p>\n<p>La jefa municipal anunci\u00f3 que \u201cen los pr\u00f3ximos 12 meses, el 30% de la ciudad contar\u00e1 con sem\u00e1foros inteligentes\u201d. Adem\u00e1s, adelant\u00f3 que pr\u00f3ximamente se desarrollar\u00e1 \u201cun proyecto de alumbrado p\u00fablico con telegesti\u00f3n\u201d.<\/p>\n<p><strong>M\u00e1s salud gratuita<\/strong><\/p>\n<p>En su mensaje ante el Concejo, la intendenta Chahla remarc\u00f3 la importancia de tener \u201cun Estado presente y eficiente\u201d que acompa\u00f1e a los vecinos. En un contexto nacional de incertidumbre, de ajustes, de intolerancia, donde se pone en duda la presencia del Estado nosotros reafirmamos nuestro compromiso y decimos s\u00ed a la presencia del Estado, porque decimos s\u00ed a la educaci\u00f3n, s\u00ed a la salud p\u00fablica y gratuita, s\u00ed a las universidades p\u00fablicas, gratuitas y de calidad\u201d.<\/p>\n<p>Con esa premisa, la jefa municipal asumi\u00f3 el compromiso de \u201cabrir el servicio de oftalmolog\u00eda en la Asistencia P\u00fablica para aquellos ni\u00f1os y adultos sin obra social puedan obtener sus lentes recetados\u201d. Adem\u00e1s, inform\u00f3 que el Municipio est\u00e1 \u201creestructurando y modernizando el Centro Interdisciplinario Municipal para la Condici\u00f3n del Espectro Autista (CIM CEA) y, en los pr\u00f3ximos d\u00edas, ser\u00e1 inaugurada la Casa Azul (en calle Alberdi 250), un espacio de contenci\u00f3n y desarrollo para muchas familias de nuestra capital\u201d que brinda un servicio gratuito y de calidad.<\/p>\n<p><strong>Seguridad alimentaria<\/strong><\/p>\n<p>La intendenta de la capital anticip\u00f3 que este a\u00f1o se avanzar\u00e1 con la puesta en funcionamiento de un Centro de Soberan\u00eda Alimentaria Municipal (SAM). \u201cEn una primera etapa, ya est\u00e1 funcionando la Panader\u00eda Municipal, que garantiza pan y tortillas para personas que requieren de nuestra asistencia. Tambi\u00e9n habr\u00e1 una Sala de Agroindustria Artesanal. Este espacio va a ampliar la posibilidad de producci\u00f3n de conservas, dulces, licores y especias mediante la capacitaci\u00f3n y la formaci\u00f3n para promover la autonom\u00eda econ\u00f3mica de todos los participantes\u201d, detall\u00f3.<\/p>\n<p><strong>Paseo del Bajo<\/strong><\/p>\n<p>La intendenta ratific\u00f3 el compromiso de avanzar este a\u00f1o con un plan de reordenamiento de la v\u00eda p\u00fablica, que incluir\u00e1 acciones para regularizar la situaci\u00f3n de los vendedores ambulantes en la zona de El Bajo. Destac\u00f3 que para avanzar con ese objetivo se proyecta una obra de gran envergadura, que se realizar\u00e1 con la colaboraci\u00f3n del Gobierno provincial, como es el Paseo El Bajo. \u201cEs una obra estrat\u00e9gica que generar\u00e1 un impacto positivo en el desarrollo econ\u00f3mico y el dise\u00f1o urban\u00edstico de la ciudad. Esto ser\u00e1 realizado con fondos provinciales y municipales\u201d, explic\u00f3 la intendenta.<\/p>\n<p><strong>Centro de<\/strong><strong>\u00a0Convenciones<\/strong><\/p>\n<p>La intendenta Chahla destac\u00f3 el trabajo conjunto que viene realizando con el gobernador Osvaldo Jaldo, quien estuvo presente en el Concejo Deliberante para acompa\u00f1arla en el acto. \u201cCon el Gobernador tenemos grandes sue\u00f1os y proyectos para San Miguel de Tucum\u00e1n. Y uno pr\u00f3ximo a concretarse es poder llevarle el gas a 1200 familias de distintos barrios de la ciudad\u201d, resalt\u00f3. La jefa municipal dijo que con el primer mandatario comparte la intenci\u00f3n de traer los grandes eventos a Tucum\u00e1n. \u201cApostamos a la concreci\u00f3n del Centro de Convenciones, una obra clave que atraer\u00e1 inversiones, generar\u00e1 empleo y posicionar\u00e1 a Tucum\u00e1n como sede de eventos nacionales e internacionales. Tenemos que decir que este proyecto ya est\u00e1 dise\u00f1ado, ahora nos encontramos en la b\u00fasqueda de inversores que crean en nuestro Tucum\u00e1n\u201d, adelant\u00f3.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La jefa municipal realiz\u00f3 una serie de anuncios en su discurso de Apertura de Sesiones Ordinarias del Concejo Deliberante capitalino. Destac\u00f3 la importancia de \u201csostener la obra p\u00fablica\u201d y de contar con \u201cun Estado presente y eficiente\u201d. Los renovados desaf\u00edos para el segundo a\u00f1o de gesti\u00f3n. Al presidir la ceremonia de apertura del 120\u00b0 Per\u00edodo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":6099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,25],"tags":[808],"class_list":["post-6098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-politica","tag-municioalidad-de-san-miguel"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6098"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6098\/revisions"}],"predecessor-version":[{"id":6101,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6098\/revisions\/6101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/6099"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}