{"id":7776,"date":"2025-04-28T15:21:54","date_gmt":"2025-04-28T13:21:54","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=7776"},"modified":"2025-04-28T15:21:54","modified_gmt":"2025-04-28T13:21:54","slug":"los-senadores-cobraran-un-sueldo-hasta-23-veces-el-salario-minimo","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2025\/04\/28\/los-senadores-cobraran-un-sueldo-hasta-23-veces-el-salario-minimo\/","title":{"rendered":"Los senadores cobrar\u00e1n un sueldo hasta 23 veces el salario m\u00ednimo"},"content":{"rendered":"<div class=\"post-content\">\n<p>En las \u00faltimas semanas se prefiri\u00f3 evitar el debate p\u00fablico sobre las dietas.<\/p>\n<\/div>\n<div class=\"box-img\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" src=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2025\/04\/periodistas-senado-desde-los-palcos.webp\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/www.parlamentario.com\/wp-content\/uploads\/2025\/04\/periodistas-senado-desde-los-palcos.webp 750w, https:\/\/www.parlamentario.com\/wp-content\/uploads\/2025\/04\/periodistas-senado-desde-los-palcos-300x200.webp 300w\" alt=\"\" width=\"750\" height=\"500\" \/><\/div>\n<div class=\"opinion\">En medio del silencio de los propios senadores -l\u00e9ase no hacer olas en tiempos tempestuosos-, los padres de la Patria recibir\u00e1n a partir del pr\u00f3ximo mes un aumento en sus dietas que elevar\u00e1 sus sueldos a m\u00e1s de 9 millones de pesos brutos.<\/div>\n<div class=\"contenido-post\">\n<p><strong>En mano, cada legislador recibir\u00e1 entre $6,5 y $7 millones, incrementando sus ingresos en m\u00e1s de un mill\u00f3n de pesos respecto al mes anterior.<\/strong><\/p>\n<p>Este aumento no fue producto de una discusi\u00f3n reciente ni de una votaci\u00f3n espec\u00edfica. Simplemente, el congelamiento de dietas que reg\u00eda desde agosto -y que hab\u00eda sido prorrogado en enero por la vicepresidenta\u00a0<strong>Victoria Villarruel<\/strong>&#8211; venci\u00f3 el pasado 31 de marzo sin que se tomaran nuevas medidas para mantenerlo. Desde entonces, los legisladores evitaron el tema en todas las instancias formales.<\/p>\n<p>El mecanismo para calcular sus sueldos se basa en el sistema de m\u00f3dulos. Hasta marzo, cada m\u00f3dulo equival\u00eda a $2225,25, pero luego de la paritaria firmada por la <strong>Asociaci\u00f3n del Personal Legislativo (APL),<\/strong> conducida por\u00a0<strong>Norberto Di Pr\u00f3spero<\/strong>, el valor subi\u00f3 a $2285. <strong>Como cada senador cobra 4000 m\u00f3dulos (2500 por dieta, 1000 por desarraigo y 500 por representaci\u00f3n), el salario bruto se dispara a $9,1 millones.<\/strong><\/p>\n<p>Cabe destacar que la \u00faltima semana APL reclam\u00f3 reabrir las paritarias a partir del hecho de que los porcentajes de aumentos otorgados han quedado por debajo de la inflaci\u00f3n. En t\u00e9rminos comparativos, esta cifra equivale a 23 veces el salario m\u00ednimo vital y m\u00f3vil de abril ($296.832) y supera 18 veces la jubilaci\u00f3n m\u00ednima con bono. Adem\u00e1s, sus ingresos quedar\u00e1n un 60% por encima de lo que percibir\u00e1n los<strong> diputados nacionales, quienes rondar\u00e1n los $5,7 millones brutos.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7779 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/04\/62927w850h567c.jpg.webp\" alt=\"\" width=\"850\" height=\"567\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/04\/62927w850h567c.jpg.webp 850w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/04\/62927w850h567c.jpg-300x200.webp 300w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/04\/62927w850h567c.jpg-768x512.webp 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/p>\n<p>Ante la resistencia social a cualquier aumento de los legisladores, dentro del Senado el asunto genera m\u00e1s incomodidad que acciones concretas. De hecho, en v\u00edsperas de la \u00faltima sesi\u00f3n, donde apenas se insinu\u00f3 la posibilidad de tratar el tema, los senadores prefirieron dedicar el debate a un homenaje al papa Francisco por su aniversario pontificio.<\/p>\n<p><strong>Villarruel, quien hab\u00eda impulsado el congelamiento de sueldos, intenta ahora despegarse del efecto de esta medida. Sin embargo, tras el vencimiento del plazo de congelamiento, la responsabilidad de actuar qued\u00f3 en manos de los senadores, quienes de momento no muestran intenci\u00f3n de frenar el incremento.<\/strong><\/p>\n<p>La pol\u00e9mica por las dietas en la C\u00e1mara alta no es nueva. Ya en abril del a\u00f1o pasado, los senadores hab\u00edan votado a mano alzada una resoluci\u00f3n que duplicaba sus ingresos, introduciendo adem\u00e1s una dieta decimotercera a modo de aguinaldo. <strong>En ese momento, elevaron sus haberes de alrededor de $2 millones a $4,5 millones brutos. La decisi\u00f3n gener\u00f3 un fuerte cruce con el Poder Ejecutivo y cr\u00edticas que a\u00fan resuenan.<\/strong><\/p>\n<p>Hoy, aunque en privado algunos legisladores admiten su preocupaci\u00f3n por el descontento social, argumentan que los costos de residir en la ciudad de Buenos Aires, lejos de sus provincias, son elevados. Incluso, varios senadores comparan sus ingresos con los de ejecutivos de empresas privadas o funcionarios judiciales, buscando relativizar el impacto de la suba.<\/p>\n<p><strong>Mientras tanto, dentro de las reuniones de Labor Parlamentaria, el debate sobre los sueldos sigue posterg\u00e1ndose.<\/strong> El oficialismo y la oposici\u00f3n coinciden en que el momento no es oportuno, pero tambi\u00e9n reconocen que no existen los votos necesarios para revertir la situaci\u00f3n.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas semanas se prefiri\u00f3 evitar el debate p\u00fablico sobre las dietas. En medio del silencio de los propios senadores -l\u00e9ase no hacer olas en tiempos tempestuosos-, los padres de la Patria recibir\u00e1n a partir del pr\u00f3ximo mes un aumento en sus dietas que elevar\u00e1 sus sueldos a m\u00e1s de 9 millones de pesos &hellip;<\/p>\n","protected":false},"author":2,"featured_media":7777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,25],"tags":[247,718,627],"class_list":["post-7776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-politica","tag-dietas","tag-senado-de-la-nacion","tag-senadores"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7776"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7776\/revisions"}],"predecessor-version":[{"id":7780,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7776\/revisions\/7780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7777"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}