{"id":9345,"date":"2025-06-26T13:25:03","date_gmt":"2025-06-26T11:25:03","guid":{"rendered":"https:\/\/cafeprensa.com.ar\/?p=9345"},"modified":"2025-06-26T13:25:03","modified_gmt":"2025-06-26T11:25:03","slug":"el-gobierno-debe-pedirle-la-renuncia-inmediata-al-presidente-del-banco-nacion","status":"publish","type":"post","link":"https:\/\/cafeprensa.com.ar\/index.php\/2025\/06\/26\/el-gobierno-debe-pedirle-la-renuncia-inmediata-al-presidente-del-banco-nacion\/","title":{"rendered":"\u201cEl gobierno debe pedirle la renuncia inmediata al presidente del Banco Naci\u00f3n"},"content":{"rendered":"<p>El diputado nacional y dirigente bancario Carlos Cisneros denunci\u00f3 <b>\u00abun grave conflicto de intereses del presidente del Banco Naci\u00f3n, Daniel Tillard, por favorecer a una empresa quebrada vinculada a su hijo\u00bb. Tambi\u00e9n critic\u00f3 el plan de cierre de sucursales impulsado por el Gobierno y advirti\u00f3 sobre \u00abun avance encubierto hacia la privatizaci\u00f3n del banco p\u00fablico m\u00e1s grande del pa\u00eds\u00bb.<\/b><\/p>\n<div>Cisneros lanz\u00f3 duras cr\u00edticas contra su presidente, Daniel Tillard, y denunci\u00f3 p\u00fablicamente \u201cun claro conflicto de intereses que no puede ser tolerado\u201d.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9347 size-full\" src=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/06\/675a0f277d4d3_728_488.jpg\" alt=\"\" width=\"728\" height=\"488\" srcset=\"https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/06\/675a0f277d4d3_728_488.jpg 728w, https:\/\/cafeprensa.com.ar\/wp-content\/uploads\/2025\/06\/675a0f277d4d3_728_488-300x201.jpg 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/div>\n<div><strong>Cisneros se\u00f1al\u00f3 que \u00abseg\u00fan se revel\u00f3 en medios nacionales, el titular del BNA orden\u00f3 la compra de bonos por $400 millones a una empresa quebrada, Aconcagua Energ\u00eda, sin el aval del directorio y con la intervenci\u00f3n directa de su hijo Ignacio Tillard, quien como colocador de la deuda se qued\u00f3 con una comisi\u00f3n del 1%\u00bb<\/strong>.<\/div>\n<div>\u201cEl Banco Naci\u00f3n no es el negocio de una familia\u201d, dispar\u00f3 Cisneros.<\/div>\n<div>\u201cEstamos frente a un caso que combina discrecionalidad, nepotismo y negocios cruzados con fondos p\u00fablicos\u201d, denunci\u00f3 Cisneros.<strong> \u201cEs inaceptable que se usen recursos del banco estatal m\u00e1s importante del pa\u00eds para salvar a empresas privadas en default y beneficiar a familiares del presidente de la entidad\u201d.<\/strong><br \/>\nEl diputado apunt\u00f3 tambi\u00e9n contra \u00abel plan de cierre de 60 sucursales que el Gobierno impulsa bajo el pretexto de \u2019eficiencia y modernizaci\u00f3n\u2019, que ya deriv\u00f3 en despidos, jubilaciones anticipadas y abandono de zonas donde el Naci\u00f3n es el \u00fanico banco operativo\u00bb.<br \/>\n<strong>\u201cEl ajuste encubierto que est\u00e1n aplicando no es para mejorar el banco. Es para vaciarlo, debilitarlo y venderlo despu\u00e9s\u201d,<\/strong> advirti\u00f3.<\/div>\n<div>Cisneros tambi\u00e9n afirm\u00f3 que \u00abno es la primera vez que el Banco Naci\u00f3n es utilizado para beneficiar a empresas privadas con v\u00ednculos pol\u00edticos\u00bb.<\/div>\n<div><strong>\u201cYa lo vimos durante el gobierno de Mauricio Macri, cuando el Banco le otorg\u00f3 cr\u00e9ditos millonarios por encima de los l\u00edmites legales a Vicentin, una empresa que termin\u00f3 defaulteando m\u00e1s de 1.500 millones de d\u00f3lares y que a\u00fan hoy sigue envuelta en causas judiciales por fraude\u201d<\/strong>, sostuvo.Y agreg\u00f3: \u201cEse modus operandi parece repetirse ahora con Aconcagua. Cambian los nombres, pero el patr\u00f3n se repite: bancos p\u00fablicos usados como caja de salvataje para empresas amigas y negocios personales\u201d.<br \/>\nCisneros refut\u00f3 adem\u00e1s \u00abla narrativa oficial que intenta justificar la transformaci\u00f3n del Naci\u00f3n en sociedad an\u00f3nima alegando que es una estructura obsoleta y deficitaria\u00bb.<\/div>\n<div><strong>\u201cLos propios balances desmienten ese relato. El Banco Naci\u00f3n es altamente rentable, con ganancias operativas de $11,4 billones en 2024 y un rol clave en el financiamiento de PyMEs, industrias, el agro y el comercio en todo el pa\u00eds. Concentra el 15% de todos los pr\u00e9stamos del sistema financiero y tiene m\u00e1s de 20 millones de cajas de ahorro activas\u201d, detall\u00f3 el legislador.<\/strong>Incluso en 2023, el banco estatal ya hab\u00eda mostrado un incremento del 155,8% en los pr\u00e9stamos comerciales, siendo la principal fuente de financiamiento para peque\u00f1as y medianas empresas. \u201c\u00bfEse es el banco que quieren cerrar? \u00bfEso es lo que les molesta?\u201d, se pregunt\u00f3 Cisneros.<br \/>\nEl dirigente sindical de La Bancaria fue contundente al cerrar su intervenci\u00f3n: <strong>\u201cNo vamos a permitir que lo usen como trampol\u00edn personal mientras ajustan al pueblo. El Banco Naci\u00f3n es soberan\u00eda econ\u00f3mica. Y no se negocia\u201d.<\/strong><\/div>\n<div>Adem\u00e1s, pidi\u00f3 que el gobierno le pida la renuncia a Daniel Tillard y exigi\u00f3 que se respete la decisi\u00f3n del Congreso, que excluy\u00f3 expresamente al BNA de la lista de empresas privatizables. <strong>\u201cLa transformaci\u00f3n en sociedad an\u00f3nima por decreto es un atajo ilegal para avanzar en la entrega del banco\u201d,<\/strong> denunci\u00f3.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El diputado nacional y dirigente bancario Carlos Cisneros denunci\u00f3 \u00abun grave conflicto de intereses del presidente del Banco Naci\u00f3n, Daniel Tillard, por favorecer a una empresa quebrada vinculada a su hijo\u00bb. Tambi\u00e9n critic\u00f3 el plan de cierre de sucursales impulsado por el Gobierno y advirti\u00f3 sobre \u00abun avance encubierto hacia la privatizaci\u00f3n del banco p\u00fablico &hellip;<\/p>\n","protected":false},"author":2,"featured_media":9346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,25],"tags":[487,2142,2143],"class_list":["post-9345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-politica","tag-carlos-cisneros","tag-daniel-tillard","tag-pte-del-banc-nacion"],"_links":{"self":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9345"}],"version-history":[{"count":1,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9345\/revisions"}],"predecessor-version":[{"id":9348,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9345\/revisions\/9348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9346"}],"wp:attachment":[{"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafeprensa.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}